{"id":10351,"date":"2025-10-09T14:51:20","date_gmt":"2025-10-09T12:51:20","guid":{"rendered":"https:\/\/computaex.eu\/?page_id=10351"},"modified":"2025-12-04T12:11:54","modified_gmt":"2025-12-04T11:11:54","slug":"connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/","title":{"rendered":"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10351\" class=\"elementor elementor-10351\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3e6f41 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"f3e6f41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29e1d3f1 elementor-widget elementor-widget-text-editor\" data-id=\"29e1d3f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\"><strong>Resumen:<\/strong><\/p><p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\" style=\"text-align: justify;\">Asesor\u00eda de Investigaci\u00f3n para el Proyecto: \u201cAn\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. CONNEXPERIENCE.\u201d, en las siguientes tareas:<\/p><ul style=\"text-align: justify;\"><li class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">Tarea 3.3.3: Dise\u00f1o y Desarrollo de Modelos de Aprendizaje Autom\u00e1tico y Aprendizaje Profundo.<\/li><li class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">Tarea 3.3.4: Entrenamiento y Evaluaci\u00f3n de los Modelos.<\/li><li class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">Tarea 3.3.5: Integraci\u00f3n de los Modelos en un Sistema de Recomendaci\u00f3n Personalizado.<\/li><\/ul><p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\" style=\"text-align: justify;\"><strong>Fuente financiaci\u00f3n: <\/strong><\/p><p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\" style=\"text-align: justify;\">Consejer\u00eda de Econom\u00eda, Empleo y Transformaci\u00f3n Digital. Decreto 57\/2023, de 24 de mayo, por el que se establecen las bases reguladoras de las ayudas destinadas a la financiaci\u00f3n de proyectos de investigaci\u00f3n industrial o desarrollo experimental realizados por peque\u00f1as y medianas empresas, en la Comunidad Aut\u00f3noma de Extremadura y se aprueba la primera convocatoria relativa a proyectos realizados por empresas de base tecnol\u00f3gica y startups.<\/p><p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\" style=\"text-align: justify;\"><strong>Empresa:<\/strong> UXHOTELES, S.L.<\/p><p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\" style=\"text-align: justify;\"><strong>Cofinanciaci\u00f3n:<\/strong> Con cargo al Programa Operativo del Fondo Europeo de Desarrollo Regional (FEDER) de Extremadura correspondiente al periodo de programaci\u00f3n (2021-2027), dentro del Objetivo Pol\u00edtico 1 \u201cUna Europa m\u00e1s competitiva e inteligente, promoviendo una transformaci\u00f3n econ\u00f3mica innovadora inteligente y una competitividad TIC regional\u201d, Prioridad 1.A: Transici\u00f3n digital e inteligente y el Objetivo Espec\u00edfico 1.1 \u201cEl desarrollo y la mejora de las capacidades de investigaci\u00f3n e innovaci\u00f3n y la asimilaci\u00f3n de tecnolog\u00edas avanzadas\u201d. El porcentaje de cofinanciaci\u00f3n de los fondos FEDER es de un 85%.<\/p><p><a href=\"https:\/\/computaex.eu\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-10341 size-full\" src=\"https:\/\/computaex.eu\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png\" alt=\"\" width=\"1147\" height=\"62\" srcset=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png 1147w, http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL-300x16.png 300w, http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL-1024x55.png 1024w, http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL-768x42.png 768w\" sizes=\"(max-width: 1147px) 100vw, 1147px\" \/><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Resumen: Asesor\u00eda de Investigaci\u00f3n para el Proyecto: \u201cAn\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[117,118,81],"tags":[],"class_list":["post-10351","page","type-page","status-publish","hentry","category-activos","category-aprendizaje-automatico","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Resumen: Asesor\u00eda de Investigaci\u00f3n para el Proyecto: \u201cAn\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T11:11:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/\",\"name\":\"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/FinanciacionGRAYOWL.png\",\"datePublished\":\"2025-10-09T12:51:20+00:00\",\"dateModified\":\"2025-12-04T11:11:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/#primaryimage\",\"url\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/FinanciacionGRAYOWL.png\",\"contentUrl\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/FinanciacionGRAYOWL.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector.\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/","og_locale":"en_US","og_type":"article","og_title":"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. - Fundaci\u00f3n COMPUTAEX","og_description":"Resumen: Asesor\u00eda de Investigaci\u00f3n para el Proyecto: \u201cAn\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. ...","og_url":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-12-04T11:11:54+00:00","og_image":[{"url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/","url":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/","name":"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector. - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/#primaryimage"},"image":{"@id":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/#primaryimage"},"thumbnailUrl":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png","datePublished":"2025-10-09T12:51:20+00:00","dateModified":"2025-12-04T11:11:54+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/#primaryimage","url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png","contentUrl":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/10\/FinanciacionGRAYOWL.png"},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/connexperience-analisis-de-la-sinergia-entre-destinos-turisticos-inteligentes-y-hoteles-para-la-mejora-de-la-experiencia-del-cliente-como-recurso-competitivo-del-sector\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"CONNEXPERIENCE: An\u00e1lisis de la Sinergia entre Destinos Tur\u00edsticos Inteligentes y Hoteles para la Mejora de la Experiencia del Cliente como recurso competitivo del sector."}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/10351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=10351"}],"version-history":[{"count":7,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/10351\/revisions"}],"predecessor-version":[{"id":10712,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/10351\/revisions\/10712"}],"up":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=10351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=10351"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=10351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}