{"id":10973,"date":"2026-02-02T08:00:53","date_gmt":"2026-02-02T07:00:53","guid":{"rendered":"https:\/\/computaex.eu\/?page_id=10973"},"modified":"2026-02-19T09:13:30","modified_gmt":"2026-02-19T08:13:30","slug":"ref-2026-2-tecnico-a-de-investigacion-y-desarrollo","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/","title":{"rendered":"REF 2026-2 T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"10973\" class=\"elementor elementor-10973\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7459449 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"7459449\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-362cb24 elementor-widget elementor-widget-text-editor\" data-id=\"362cb24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: start;\"><strong>REF 2026-2\u00a0<\/strong><span style=\"text-align: start;\"><b>T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo<\/b><\/span><\/p><p><span style=\"font-size: 0.875rem;\">La Fundaci\u00f3n COMPUTAEX oferta un puesto :<\/span><\/p><ul><li><b>T\u00e9cnico\/a de apoyo a la investigaci\u00f3n\u00a0(Ref. 2026-2).<\/b><\/li><\/ul><p>Todos los detalles de la convocatoria pueden ser consultados en las bases.<\/p><p><strong>Solicitudes:<\/strong><br \/>Las solicitudes para participar en el proceso de selecci\u00f3n se formular\u00e1n mediante el modelo oficial (Anexo I) debidamente cumplimentadas y firmadas, y deber\u00e1n ir acompa\u00f1adas de la siguiente documentaci\u00f3n:<\/p><ul><li><a href=\"\/wp-content\/uploads\/2025\/12\/Solicitud_ref_2025-9.pdf\">\u00a0<\/a><a href=\"https:\/\/computaex.eu\/wp-content\/uploads\/2026\/02\/solicitud_ref_2026-2.pdf\">Anexo I &#8211; Solicitud_ref_2026-2<\/a>\u00a0<img decoding=\"async\" style=\"display: inline-block; vertical-align: middle; margin-left: 4px;\" src=\"\/wp-content\/uploads\/2025\/07\/icono-pdf-e1753341024523.png\" alt=\"\" width=\"16\" height=\"20\" \/><\/li><li>Copia del Documento Nacional de Identidad o equivalente<\/li><li>Copia del t\u00edtulo oficial exigido o resguardo de solicitud del mismo.<\/li><li>Curr\u00edculum Vitae detallado, junto con la documentaci\u00f3n acreditativa de los m\u00e9ritos alegados.<\/li><li>Informe de vida laboral actualizado.<\/li><li><a href=\"\/wp-content\/uploads\/2025\/07\/informacion_y_tratamiento_de_datos_ref_2025-3.pdf\">Anexo II &#8211; Tratamiento de datos<\/a> <img decoding=\"async\" style=\"display: inline-block; vertical-align: middle; margin-left: 4px;\" src=\"\/wp-content\/uploads\/2025\/07\/icono-pdf-e1753341024523.png\" alt=\"\" width=\"16\" height=\"20\" \/><\/li><\/ul><hr \/><p><strong>Fases del proceso:<\/strong><\/p><ul><li>Plazo presentaci\u00f3n de solicitudes:<strong>\u00a0 05 de febrero de 2026.<\/strong><\/li><li>Listado provisional de personas admitidas y excluidas:<span style=\"font-weight: bolder;\">\u00a006 de febrero de 2026. Subsanaciones hasta las 23:59 horas del d\u00eda 09 de febrero de 2026.<\/span><\/li><li>Listado definitivo de personas admitidas y excluidas:<span style=\"font-weight: bolder;\"> 10 de febrero de 2026.<\/span><\/li><li>Baremo definitivo:<span style=\"font-weight: bolder;\"> 16 de febrero de 2026.<\/span><\/li><li>Relaci\u00f3n de personas aprobadas:<span style=\"font-weight: bolder;\"> 17 de febrero de 2026.<\/span><\/li><li>Resoluci\u00f3n de contrataci\u00f3n:<span style=\"font-weight: bolder;\">\u00a019 de febrero de 2026.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dd19b4 elementor-widget elementor-widget-tabla_descargas\" data-id=\"5dd19b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;boton_anadir_ids&quot;:&quot;10974,11019,11041,11057,11061,11073&quot;,&quot;fechas_personalizadas&quot;:&quot;{}&quot;}\" data-widget_type=\"tabla_descargas.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tabla-descargas-container\" data-widget-id=\"5dd19b4\"><table class=\"tabla-descargas\"><thead><tr><th class=\"sortable\" data-sort=\"nombre\">Archivo <span class=\"sort-arrow\"><\/span><\/th><th class=\"sortable\" data-sort=\"tamano\">Size <span class=\"sort-arrow\"><\/span><\/th><th class=\"sortable asc\" data-sort=\"fecha\">Date <span class=\"sort-arrow asc\"><\/span><\/th><th style=\"text-align: center;\">Ver<\/th><th>Descargar<\/th><\/tr><\/thead><tr data-nombre=\"BasesContratacion-Ref-2026-2_signed\" data-tamano=\"492541\" data-fecha=\"2026-02-02\"><td><div class=\"archivo-info\"><div class=\"titulo-archivo\">BasesContratacion-Ref-2026-2_signed<\/div><div class=\"nombre-archivo\">BasesContratacion-Ref-2026-2_signed.pdf<\/div><\/div><\/td><td>481 KB<\/td><td>02\/02\/2026<\/td><td style=\"text-align: center;\"><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/BasesContratacion-Ref-2026-2_signed.pdf\" class=\"boton-ver\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ver documento\">\ud83d\udc41<\/a><\/td><td><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/BasesContratacion-Ref-2026-2_signed.pdf\" class=\"boton-descarga\" download=\"BasesContratacion-Ref-2026-2_signed.pdf\">\u2193 Descargar<\/a><\/td><\/tr><tr data-nombre=\"Listado Provisional Personas Admitidas y Excluidas-Ref-2026-2_signed\" data-tamano=\"261625\" data-fecha=\"2026-02-06\"><td><div class=\"archivo-info\"><div class=\"titulo-archivo\">Listado Provisional Personas Admitidas y Excluidas-Ref-2026-2_signed<\/div><div class=\"nombre-archivo\">Listado-Provisional-Personas-Admitidas-y-Excluidas-Ref-2026-2_signed.pdf<\/div><\/div><\/td><td>255 KB<\/td><td>06\/02\/2026<\/td><td style=\"text-align: center;\"><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Listado-Provisional-Personas-Admitidas-y-Excluidas-Ref-2026-2_signed.pdf\" class=\"boton-ver\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ver documento\">\ud83d\udc41<\/a><\/td><td><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Listado-Provisional-Personas-Admitidas-y-Excluidas-Ref-2026-2_signed.pdf\" class=\"boton-descarga\" download=\"Listado-Provisional-Personas-Admitidas-y-Excluidas-Ref-2026-2_signed.pdf\">\u2193 Descargar<\/a><\/td><\/tr><tr data-nombre=\"Listado Definitivo Personas Admitidas y Excluidas y Baremo-Ref-2026-2_signed\" data-tamano=\"269150\" data-fecha=\"2026-02-10\"><td><div class=\"archivo-info\"><div class=\"titulo-archivo\">Listado Definitivo Personas Admitidas y Excluidas y Baremo-Ref-2026-2_signed<\/div><div class=\"nombre-archivo\">Listado-Definitivo-Personas-Admitidas-y-Excluidas-y-Baremo-Ref-2026-2_signed.pdf<\/div><\/div><\/td><td>263 KB<\/td><td>10\/02\/2026<\/td><td style=\"text-align: center;\"><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Listado-Definitivo-Personas-Admitidas-y-Excluidas-y-Baremo-Ref-2026-2_signed.pdf\" class=\"boton-ver\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ver documento\">\ud83d\udc41<\/a><\/td><td><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Listado-Definitivo-Personas-Admitidas-y-Excluidas-y-Baremo-Ref-2026-2_signed.pdf\" class=\"boton-descarga\" download=\"Listado-Definitivo-Personas-Admitidas-y-Excluidas-y-Baremo-Ref-2026-2_signed.pdf\">\u2193 Descargar<\/a><\/td><\/tr><tr data-nombre=\"BaremoDefinitivo-Ref-2026-2_signed\" data-tamano=\"299142\" data-fecha=\"2026-02-16\"><td><div class=\"archivo-info\"><div class=\"titulo-archivo\">BaremoDefinitivo-Ref-2026-2_signed<\/div><div class=\"nombre-archivo\">BaremoDefinitivo-Ref-2026-2_signed.pdf<\/div><\/div><\/td><td>292 KB<\/td><td>16\/02\/2026<\/td><td style=\"text-align: center;\"><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/BaremoDefinitivo-Ref-2026-2_signed.pdf\" class=\"boton-ver\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ver documento\">\ud83d\udc41<\/a><\/td><td><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/BaremoDefinitivo-Ref-2026-2_signed.pdf\" class=\"boton-descarga\" download=\"BaremoDefinitivo-Ref-2026-2_signed.pdf\">\u2193 Descargar<\/a><\/td><\/tr><tr data-nombre=\"Relacio\u0301n de Personas Aprobadas-Ref-2026-2_signed\" data-tamano=\"302705\" data-fecha=\"2026-02-17\"><td><div class=\"archivo-info\"><div class=\"titulo-archivo\">Relacio\u0301n de Personas Aprobadas-Ref-2026-2_signed<\/div><div class=\"nombre-archivo\">Relacion-de-Personas-Aprobadas-Ref-2026-2_signed.pdf<\/div><\/div><\/td><td>296 KB<\/td><td>17\/02\/2026<\/td><td style=\"text-align: center;\"><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Relacion-de-Personas-Aprobadas-Ref-2026-2_signed.pdf\" class=\"boton-ver\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ver documento\">\ud83d\udc41<\/a><\/td><td><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Relacion-de-Personas-Aprobadas-Ref-2026-2_signed.pdf\" class=\"boton-descarga\" download=\"Relacion-de-Personas-Aprobadas-Ref-2026-2_signed.pdf\">\u2193 Descargar<\/a><\/td><\/tr><tr data-nombre=\"1234\" data-tamano=\"288065\" data-fecha=\"2026-02-19\"><td><div class=\"archivo-info\"><div class=\"titulo-archivo\">1234<\/div><div class=\"nombre-archivo\">Resolucion-de-Contratacion-Ref-2026-2_signed.pdf<\/div><\/div><\/td><td>281 KB<\/td><td>19\/02\/2026<\/td><td style=\"text-align: center;\"><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Resolucion-de-Contratacion-Ref-2026-2_signed.pdf\" class=\"boton-ver\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Ver documento\">\ud83d\udc41<\/a><\/td><td><a href=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2026\/02\/Resolucion-de-Contratacion-Ref-2026-2_signed.pdf\" class=\"boton-descarga\" download=\"Resolucion-de-Contratacion-Ref-2026-2_signed.pdf\">\u2193 Descargar<\/a><\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>REF 2026-2\u00a0T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo La Fundaci\u00f3n COMPUTAEX oferta un puesto : T\u00e9cnico\/a de apoyo a la investigaci\u00f3n\u00a0(Ref. 2026-2). Todos los detalles de la convocatoria pueden ser consultados en &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":7859,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[109,105],"tags":[],"class_list":["post-10973","page","type-page","status-publish","hentry","category-109","category-empleo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REF 2026-2 T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REF 2026-2 T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"REF 2026-2\u00a0T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo La Fundaci\u00f3n COMPUTAEX oferta un puesto : T\u00e9cnico\/a de apoyo a la investigaci\u00f3n\u00a0(Ref. 2026-2). Todos los detalles de la convocatoria pueden ser consultados en ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-19T08:13:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/en\\\/empleo\\\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\\\/\",\"url\":\"https:\\\/\\\/www.computaex.eu\\\/en\\\/empleo\\\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\\\/\",\"name\":\"REF 2026-2 T\u00e9cnico\\\/a de Investigaci\u00f3n y Desarrollo - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2026-02-02T07:00:53+00:00\",\"dateModified\":\"2026-02-19T08:13:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/en\\\/empleo\\\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.eu\\\/en\\\/empleo\\\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/en\\\/empleo\\\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleo\",\"item\":\"https:\\\/\\\/computaex.es\\\/empleo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"REF 2026-2 T\u00e9cnico\\\/a de Investigaci\u00f3n y Desarrollo\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REF 2026-2 T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/","og_locale":"en_US","og_type":"article","og_title":"REF 2026-2 T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo - Fundaci\u00f3n COMPUTAEX","og_description":"REF 2026-2\u00a0T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo La Fundaci\u00f3n COMPUTAEX oferta un puesto : T\u00e9cnico\/a de apoyo a la investigaci\u00f3n\u00a0(Ref. 2026-2). Todos los detalles de la convocatoria pueden ser consultados en ...","og_url":"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2026-02-19T08:13:30+00:00","og_image":[{"width":1024,"height":403,"url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/","url":"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/","name":"REF 2026-2 T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2026-02-02T07:00:53+00:00","dateModified":"2026-02-19T08:13:30+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.eu\/en\/empleo\/ref-2026-2-tecnico-a-de-investigacion-y-desarrollo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Empleo","item":"https:\/\/computaex.es\/empleo\/"},{"@type":"ListItem","position":3,"name":"REF 2026-2 T\u00e9cnico\/a de Investigaci\u00f3n y Desarrollo"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/10973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=10973"}],"version-history":[{"count":30,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/10973\/revisions"}],"predecessor-version":[{"id":11076,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/10973\/revisions\/11076"}],"up":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/7859"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=10973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=10973"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=10973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}