{"id":2117,"date":"2024-04-10T12:46:08","date_gmt":"2024-04-10T10:46:08","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2117"},"modified":"2025-08-29T12:07:42","modified_gmt":"2025-08-29T10:07:42","slug":"proyecto-miliac","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/proyectos\/proyecto-miliac\/","title":{"rendered":"MILIAC"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<p>C\u00e9nitS-COMPUTAEX team.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>La inteligencia artificial es la capacidad de un sistema inform\u00e1tico de imitar funciones cognitivas humanas como el aprendizaje o la soluci\u00f3n de problemas, utilizando como base las matem\u00e1ticas y la l\u00f3gica. Los sistemas basados en IA hacen predicciones o realizan acciones bas\u00e1ndose en los patrones identificados en los datos disponibles y poseen la capacidad de aprender de sus errores para ser m\u00e1s precisos. Estas capacidades han transformado a la inteligencia artificial en una de las tecnolog\u00edas m\u00e1s importantes de la actualidad capaz de permear en pr\u00e1cticamente todos los \u00e1mbitos de la sociedad, destacando su papel en el desarrollo empresarial donde se ha consolidado como una fuente de innovaci\u00f3n y tracci\u00f3n.<\/p>\n<p>La Fundaci\u00f3n COMPUTAEX dispone, desde 2019, del supercomputador LUSITANIA III. Se trata de una infraestructura especialmente dise\u00f1ada para la prestaci\u00f3n de servicios de inteligencia artificial. Esta infraestructura ha permitido a la fundaci\u00f3n participar en numerosos proyectos basados en IA y en campos tan diversos como son la salud, la agroalimentaci\u00f3n, la construcci\u00f3n o la energ\u00eda. Estas experiencias previas y la disponibilidad de LUSITANIA III ha derivado en que, aproximadamente, el 80 % de las solicitudes de recursos realizadas al centro en el \u00faltimo a\u00f1o estaban directamente relacionadas con la inteligencia artificial. Este hecho evidencia, a su vez, el creciente inter\u00e9s que ha despertado esta tecnolog\u00eda en los \u00faltimos a\u00f1os.<\/p>\n<p>Sin embargo, este renovado inter\u00e9s ha revelado ciertas carencias en la infraestructura y servicios disponibles. En concreto, la infraestructura actual no dispone de algunas de las herramientas solicitadas, las versiones disponibles no siempre satisfacen las necesidades demandadas y es necesario el despliegue de nuevos servicios m\u00e1s all\u00e1 de la provisi\u00f3n de los recursos, pensando, en este \u00faltimo caso, en empresas que quieran incorporar la inteligencia artificial a sus procesos productivos pero no dispongan de experiencia previa. Esta situaci\u00f3n limita de manera importante las solicitudes que pueden ser convenientemente atendidas desde la fundaci\u00f3n y suponen un grave problema que debe ser abordado.<\/p>\n<p>El objetivo del proyecto MILIAC consiste en facilitar, promover y atraer la inversi\u00f3n en investigaci\u00f3n, desarrollo e innovaci\u00f3n por parte del tejido empresarial extreme\u00f1o mediante la integraci\u00f3n en sus procesos productivos de servicios de inteligencia artificial de alto valor a\u00f1adido provistos por la infraestructura de LUSITANIA. Se trata, por tanto, de llevar a cabo las acciones necesarias para adecuar la infraestructura de inteligencia artificial y ofrecer mejores servicios que redunden en un retorno econ\u00f3mico para su mantenimiento. Entre estas acciones se contempla el desarrollo de nuevos servicios basados en IA, la capacitaci\u00f3n del equipo t\u00e9cnico del centro, la modernizaci\u00f3n de la propia infraestructura, la difusi\u00f3n de estos nuevos servicios y la captaci\u00f3n de nuevas empresas y usuarios.<\/p>\n<p>La ejecuci\u00f3n del presente proyecto supondr\u00e1 la disponibilidad de una infraestructura de inteligencia artificial actualizada y eficiente que garantizar\u00e1 una mejor prestaci\u00f3n de servicios por parte del centro C\u00e9nitS, as\u00ed como su sostenibilidad, no solo a corto, sino tambi\u00e9n a medio y largo plazo. Los nuevos servicios y capacidades adquiridas favorecer\u00e1, a su vez, el establecimiento de colaboraciones p\u00fablico-privadas para la elaboraci\u00f3n de proyectos de investigaci\u00f3n, desarrollo e innovaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>El objetivo general del proyecto consiste en facilitar, promover y atraer la inversi\u00f3n en investigaci\u00f3n, desarrollo e innovaci\u00f3n por parte del tejido empresarial extreme\u00f1o mediante la integraci\u00f3n en sus procesos productivos de servicios de inteligencia artificial de alto valor a\u00f1adido provistos por la infraestructura de LUSITANIA. Se pretende, por tanto, disponer de una infraestructura cient\u00edfico-t\u00e9cnica moderna capaz de captar inversiones privadas para la transformaci\u00f3n o el desarrollo, dentro de las empresas, de nuevos servicios basados en inteligencia artificial. Esta atracci\u00f3n de capital privado contribuir\u00e1, a su vez, a la sostenibilidad en el tiempo del centro C\u00e9nitS ya que permitir\u00e1 reducir el coste asociado al mantenimiento de la propia infraestructura. Adem\u00e1s, la infraestructura modernizada y los servicios prestados por la misma, especialmente aquellos relacionados con IA, favorecer\u00e1n la creaci\u00f3n de consorcios p\u00fablico-privados para la presentaci\u00f3n de propuestas de proyectos competitivos a nivel nacional y europeo.<\/p>\n<p>Para alcanzar tal objetivo es necesario actualizar la infraestructura de inteligencia artificial del centro C\u00e9nitS, as\u00ed como prepararla y configurarla con el fin de facilitar la integraci\u00f3n del equipamiento a incorporar durante el a\u00f1o 2023 (Mare-Nostrum-IV y LUSITANIA IV). Tambi\u00e9n es prioritario potenciar la capacitaci\u00f3n del personal de C\u00e9nitS en inteligencia artificial y en sistemas de almacenamiento como elemento clave para la prestaci\u00f3n del mejor servicio posible.<br \/>\nUna vez est\u00e9n disponibles los servicios de inteligencia artificial y se hayan adquirido los conocimientos necesarios para su adecuada prestaci\u00f3n, se propone realizar m\u00faltiples acciones de difusi\u00f3n como la participaci\u00f3n en eventos de distinta \u00edndole o la realizaci\u00f3n de acciones formativas dirigidas a potenciales usuarios (empresas, investigadores, etc.), en las que se expliquen los servicios prestados por C\u00e9nitS (supercomputaci\u00f3n, inteligencia artificial, etc.), el software y las herramientas disponibles y c\u00f3mo hacer uso de ellos.<\/p>\n<p><strong>El objetivo general del proyecto se puede desglosar en los siguientes objetivos espec\u00edficos:<\/strong><\/p>\n<p><strong>O1. Desarrollar nuevos servicios basados en inteligencia artificial:<\/strong><\/p>\n<ul>\n<li>Mediante la utilizaci\u00f3n de la infraestructura de LUSITANIA como soporte para ello y la capacitaci\u00f3n del personal t\u00e9cnico de C\u00e9nitS que dise\u00f1ar\u00e1, implementar\u00e1 y dar\u00e1 soporte a tales servicios.<\/li>\n<\/ul>\n<p><strong>O2. Garantizar la sostenibilidad de la infraestructura cient\u00edfico-t\u00e9cnica de LUSITANIA:<\/strong><\/p>\n<ul>\n<li>Mediante la captaci\u00f3n de capital privado impulsada por la actualizaci\u00f3n de la infraestructura de LUSITANIA y el despliegue sobre ella de nuevos servicios de alto valor a\u00f1adido de especial utilidad para las empresas de la regi\u00f3n.<\/li>\n<\/ul>\n<p><strong>O3. Promover y atraer inversi\u00f3n en I+D+i en la regi\u00f3n:<\/strong><\/p>\n<ul>\n<li>Mediante la celebraci\u00f3n de jornadas formativas y de difusi\u00f3n y la participaci\u00f3n activa en eventos con potenciales usuarios en los que mostrar a las empresas las ventajas competitivas de incorporar estos tipos de servicios a sus procesos productivos.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-metodologia field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Metodolog\u00eda:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Las acciones a realizar en el presente proyecto pueden agruparse en 4 paquetes de trabajo fundamentalmente. El primer paquete de trabajo se corresponde con aquellas tareas relacionadas con la gesti\u00f3n y coordinaci\u00f3n del proyecto, se trata de un paquete de trabajo que permanecer\u00e1 activo durante todo el proyecto.<\/p>\n<p>El segundo paquete de trabajo est\u00e1 relacionado con la formaci\u00f3n del equipo t\u00e9cnico de C\u00e9nitS en los diferentes componentes de los sistemas implicados en la actualizaci\u00f3n de la infraestructura de LUSITANIA y en el desarrollo de servicios de inteligencia artificial. En la mayor\u00eda de los casos ser\u00e1 un proceso de autoformaci\u00f3n a partir de documentaci\u00f3n verificada o de los manuales del fabricante, excepto para el sistema de almacenamiento para el que, al tratarse del sistema m\u00e1s cr\u00edtico de los afectados por la actualizaci\u00f3n, se prev\u00e9 la realizaci\u00f3n por parte del equipo t\u00e9cnico de C\u00e9nitS de un curso de especializaci\u00f3n muy espec\u00edfico impartido por una consultora contrastada.<\/p>\n<p>El tercer paquete de trabajo consiste en la realizaci\u00f3n de las distintas actualizaciones en s\u00ed, la prueba de los sistemas actualizados y la configuraci\u00f3n de los mismos de cara a la provisi\u00f3n de servicios de inteligencia artificial y la futura ampliaci\u00f3n del equipamiento.<\/p>\n<p>El \u00faltimo paquete de trabajo engloba aquellas tareas relacionadas con la difusi\u00f3n de los servicios prestados en C\u00e9nitS en especial aquellos relacionados con la inteligencia artificial, la b\u00fasqueda activa de nuevos usuarios y la impartici\u00f3n de formaci\u00f3n sobre la utilizaci\u00f3n de los recursos del centro a usuarios actuales y potenciales.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-financiacion field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Sources of funding:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p style=\"text-align: justify;\">En el DOE n.\u00ba 67 de 10 de abril de 2023, se public\u00f3 el convenio por el que se formaliz\u00f3 la transferencia espec\u00edfica a favor de la Fundaci\u00f3n Computaci\u00f3n y Tecnolog\u00edas Avanzadas de Extremadura (COMPUTAEX) para la realizaci\u00f3n del proyecto \u201cDesarrollo\u00a0de\u00a0Proyectos de Investigaci\u00f3n en Supercomputaci\u00f3n &#8211; Proyecto\u00a0MILIAC\u201d en el ejercicio 2023.<\/p>\n<p style=\"text-align: justify;\">El proyecto MILIAC aprobado por la Direcci\u00f3n General de Agenda Digital (Consejer\u00eda de Econom\u00eda, Ciencia y Agenda Digital) de la Junta de Extremadura, en el marco del Programa 332A \u201cTecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones\u201d, cofinanciado en un 80% por el Fondo Europeo de Desarrollo Regional (FEDER).<\/p>\n<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2025\/01\/logos-miliac.png\" alt=\"logos-miliac.png\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Equipo C\u00e9nitS-COMPUTAEX. Descripci\u00f3n:\u00a0 La inteligencia artificial es la capacidad de un sistema inform\u00e1tico de imitar funciones cognitivas humanas como el aprendizaje o la soluci\u00f3n de problemas, utilizando como base &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[104,81],"tags":[],"class_list":["post-2117","page","type-page","status-publish","hentry","category-ciencias-informaticas-y-de-comunicaciones","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MILIAC - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MILIAC - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Equipo C\u00e9nitS-COMPUTAEX. Descripci\u00f3n:\u00a0 La inteligencia artificial es la capacidad de un sistema inform\u00e1tico de imitar funciones cognitivas humanas como el aprendizaje o la soluci\u00f3n de problemas, utilizando como base ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T10:07:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-miliac\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-miliac\\\/\",\"name\":\"MILIAC - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-10T10:46:08+00:00\",\"dateModified\":\"2025-08-29T10:07:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-miliac\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-miliac\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-miliac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MILIAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MILIAC - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/","og_locale":"en_US","og_type":"article","og_title":"MILIAC - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Equipo C\u00e9nitS-COMPUTAEX. Descripci\u00f3n:\u00a0 La inteligencia artificial es la capacidad de un sistema inform\u00e1tico de imitar funciones cognitivas humanas como el aprendizaje o la soluci\u00f3n de problemas, utilizando como base ...","og_url":"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T10:07:42+00:00","og_image":[{"width":1024,"height":403,"url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/","url":"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/","name":"MILIAC - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-10T10:46:08+00:00","dateModified":"2025-08-29T10:07:42+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/proyecto-miliac\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/proyecto-miliac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"MILIAC"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2117"}],"version-history":[{"count":4,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2117\/revisions"}],"predecessor-version":[{"id":8490,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2117\/revisions\/8490"}],"up":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2117"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}