{"id":2406,"date":"2024-04-11T08:49:02","date_gmt":"2024-04-11T06:49:02","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2406"},"modified":"2025-08-29T11:57:24","modified_gmt":"2025-08-29T09:57:24","slug":"proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/","title":{"rendered":"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias."},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez (Investigador principal). Fundaci\u00f3n COMPUTAEX.<\/li>\n<li>Silvia Romero Chala. Hospital San Pedro de Alc\u00e1ntara.<\/li>\n<li>Jonathan G\u00f3mez Raja. Fundesalud.<\/li>\n<li>Jos\u00e9 Antonio Garc\u00eda Trujillo. Hospital San Pedro de Alc\u00e1ntara.<\/li>\n<li>Felipe Lemus Prieto. Fundaci\u00f3n COMPUTAEX.<\/li>\n<li>Alfonso L\u00f3pez Rourich. Fundaci\u00f3n COMPUTAEX.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-logo field-type-image field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\"><a class=\"colorbox init-colorbox-processed cboxElement\" title=\"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias.\" href=\"https:\/\/www.cenits.es\/wp-content\/uploads\/2025\/01\/logo_heritagen_0.jpeg\" data-colorbox-gallery=\"\" data-cbox-img-attrs=\"{&quot;title&quot;: &quot;&quot;, &quot;alt&quot;: &quot;&quot;}\"><img decoding=\"async\" title=\"\" src=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/logo_heritagen_0.jpeg?itok=zCO9qWFT\" alt=\"\" width=\"185\" height=\"96\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Description:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<p>Se estima que aproximadamente 1 de cada 200 nacimientos pueden verse afectados por las 6.000 enfermedades monog\u00e9nicas conocidas. Establecer la patogenicidad de las mutaciones detectadas mediante t\u00e9cnicas de secuenciaci\u00f3n masiva o ultrasecuenciaci\u00f3n (NGS, NextGeneration Sequencing) en la secuencia de los genes implicados ser\u00e1 de vital importancia para el desarrollo de terapias enmarcadas en el concepto Precision Medicine.<\/p>\n<p>No obstante, la falta de acceso a informaci\u00f3n sobre esas variaciones hace que su patogenicidad se desconozca (VUS, V ariant of Uncertain Significance ). El porcentaje de VUS puede ser reducido accediendo a la mayor cantidad de informaci\u00f3n sobre el gen relacionado con la enfermedad investigada, donde cobran especial importancia las variaciones encontradas en el mismo. El principal problema es que la informaci\u00f3n se encuentra dispersa, lo cual dificulta el acceso a la misma y supone un gasto econ\u00f3mico y un aumento de la dificultad procesando la informaci\u00f3n.<\/p>\n<p>Una de esas fuentes de informaci\u00f3n es la geneal\u00f3gica, la cual resulta de gran utilidad en el estudio de la incidencia de enfermedades hereditarias en el seno de una familia, en consultas de consejo gen\u00e9tico. No obstante, el patrimonio documental de las poblaciones se puede encontrar tambi\u00e9n disperso o bajo acceso limitado o nulo, por lo que la informaci\u00f3n geneal\u00f3gica se limita a la proporcionada por pacientes cuando solicitan una consulta.<\/p>\n<p>El objetivo del proyecto es estudiar los beneficios de la unificaci\u00f3n de fuentes de informaci\u00f3n heterog\u00e9neas al estudio de enfermedades hereditarias (espec\u00edficamente el patrimonio geneal\u00f3gico e informaci\u00f3n gen\u00e9tica), lo que servir\u00e1 para reducir la ratio de variables de significado incierto detectadas en estudios de secuenciaci\u00f3n masiva. Para ello, se propone enfocar el estudio a un conjunto de personas de una poblaci\u00f3n relevante desde el punto de vista gen\u00e9tico, para secuenciar su genoma (concretamente los genes asociados a la enfermedad elegida) y unificarlo con su informaci\u00f3n geneal\u00f3gica.<\/p>\n<p>Para gestionar y analizar la informaci\u00f3n, as\u00ed como para extraer conocimiento de la misma, se plantea el uso de recursos de supercomputaci\u00f3n en combinaci\u00f3n con t\u00e9nicas de big data. As\u00ed, mediante t\u00e9cnicas de HPC (High Performance Computing ), se procesar\u00e1n los datos y secuencias gen\u00e9ticas en el menor tiempo posible, garantizando a su vez el almacenamiento, la seguridad y la alta disponibilidad de la informaci\u00f3n con la que se trabaja.<\/p>\n<p>Por otra parte, se tendr\u00e1 en cuenta el uso de formatos estandarizados de informaci\u00f3n, as\u00ed como los aspectos \u00e9ticos derivados de la realizaci\u00f3n de tratamientos relacionados con la salud.<\/p>\n<p>La informaci\u00f3n de alto nivel generada seguir\u00e1 la filosof\u00eda opendata, cumpliendo siempre con la legislaci\u00f3n vigente en materia de seguridad y protecci\u00f3n de la informaci\u00f3n. As\u00ed mismo, los datos se pondr\u00e1n a disposici\u00f3n de los usuarios a trav\u00e9s de servicios desplegados mediante el paradigma del cloud computing.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-financiacion field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Sources of funding:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li style=\"text-align: justify;\">Proyecto cofinanciado por la Junta de Extremadura y el Fondo Europeo de Desarrollo Regional (FEDER) de Extremadura al 80 %, dentro del Objetivo Tem\u00e1tico 01 \u201cRefuerzo de la investigaci\u00f3n, el desarrollo tecnol\u00f3gico y la innovaci\u00f3n\u201d, a trav\u00e9s de la convocatoria de ayudas destinadas a la realizaci\u00f3n de proyectos de investigaci\u00f3n, orientados hacia las \u00e1reas estrat\u00e9gicas de la econom\u00eda regional contempladas en el V Plan Regional de I+D+i (2014-2017), en los centros p\u00fablicos de I+D+i de la Comunidad Aut\u00f3noma de Extremadura, al amparo del Decreto 68\/2016 de 6 de junio.<\/li>\n<\/ul>\n<p><center><img decoding=\"async\" style=\"width: 100px; height: 121px;\" src=\"\/wp-content\/uploads\/2025\/01\/feder_2017.png\" alt=\"\" \/>\u00a0 \u00a0 \u00a0<img decoding=\"async\" style=\"width: 276px; height: 100px;\" src=\"\/wp-content\/uploads\/2025\/01\/juntaex.jpg\" alt=\"\" \/><\/center><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez (Investigador principal). Fundaci\u00f3n COMPUTAEX. Silvia Romero Chala. Hospital San Pedro de Alc\u00e1ntara. Jonathan G\u00f3mez Raja. Fundesalud. Jos\u00e9 Antonio Garc\u00eda Trujillo. Hospital San Pedro de Alc\u00e1ntara. &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[103,81],"tags":[],"class_list":["post-2406","page","type-page","status-publish","hentry","category-ciencias-de-la-vida","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias. - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias. - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez (Investigador principal). Fundaci\u00f3n COMPUTAEX. Silvia Romero Chala. Hospital San Pedro de Alc\u00e1ntara. Jonathan G\u00f3mez Raja. Fundesalud. Jos\u00e9 Antonio Garc\u00eda Trujillo. Hospital San Pedro de Alc\u00e1ntara. ...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T09:57:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/logo_heritagen_0.jpeg?itok=zCO9qWFT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/\",\"url\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/\",\"name\":\"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias. - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cenits.es\\\/sites\\\/cenits.es\\\/files\\\/styles\\\/proyecto\\\/public\\\/proyectos\\\/logo_heritagen_0.jpeg?itok=zCO9qWFT\",\"datePublished\":\"2024-04-11T06:49:02+00:00\",\"dateModified\":\"2025-08-29T09:57:24+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cenits.es\\\/sites\\\/cenits.es\\\/files\\\/styles\\\/proyecto\\\/public\\\/proyectos\\\/logo_heritagen_0.jpeg?itok=zCO9qWFT\",\"contentUrl\":\"https:\\\/\\\/www.cenits.es\\\/sites\\\/cenits.es\\\/files\\\/styles\\\/proyecto\\\/public\\\/proyectos\\\/logo_heritagen_0.jpeg?itok=zCO9qWFT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias.\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias. - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/","og_locale":"en_US","og_type":"article","og_title":"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias. - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez (Investigador principal). Fundaci\u00f3n COMPUTAEX. Silvia Romero Chala. Hospital San Pedro de Alc\u00e1ntara. Jonathan G\u00f3mez Raja. Fundesalud. Jos\u00e9 Antonio Garc\u00eda Trujillo. Hospital San Pedro de Alc\u00e1ntara. ...","og_url":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T09:57:24+00:00","og_image":[{"url":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/logo_heritagen_0.jpeg?itok=zCO9qWFT","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/","url":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/","name":"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias. - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/#primaryimage"},"image":{"@id":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/logo_heritagen_0.jpeg?itok=zCO9qWFT","datePublished":"2024-04-11T06:49:02+00:00","dateModified":"2025-08-29T09:57:24+00:00","breadcrumb":{"@id":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/#primaryimage","url":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/logo_heritagen_0.jpeg?itok=zCO9qWFT","contentUrl":"https:\/\/www.cenits.es\/sites\/cenits.es\/files\/styles\/proyecto\/public\/proyectos\/logo_heritagen_0.jpeg?itok=zCO9qWFT"},{"@type":"BreadcrumbList","@id":"http:\/\/computaex.eu\/en\/proyectos\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"HeritaGen: Ultrasecuenciaci\u00f3n y supercomputaci\u00f3n para la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o. Aplicaci\u00f3n al estudio de enfermedades hereditarias."}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2406"}],"version-history":[{"count":6,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2406\/revisions"}],"predecessor-version":[{"id":8452,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2406\/revisions\/8452"}],"up":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2406"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}