{"id":2648,"date":"2024-04-11T09:48:06","date_gmt":"2024-04-11T07:48:06","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2648"},"modified":"2025-08-29T12:03:11","modified_gmt":"2025-08-29T10:03:11","slug":"proyecto-calculos-ab-initio","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/","title":{"rendered":"C\u00e1lculos AB-Initio"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<ul>\n<li><strong>Javier S\u00e1nchez Montero<\/strong>.\u00a0<a href=\"http:\/\/www.ietcc.csic.es\/\">Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja<\/a>.\u00a0<a href=\"http:\/\/www.csic.es\/web\/guest\/home\">CSIC<\/a>.<\/li>\n<li><strong>Pedro L. de Andr\u00e9s<\/strong>.\u00a0<a href=\"http:\/\/www.ietcc.csic.es\/\">Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja<\/a>.\u00a0<a href=\"http:\/\/www.csic.es\/web\/guest\/home\">CSIC<\/a>.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Existe evidencia de la variaci\u00f3n de par\u00e1metros mec\u00e1nicos, pero la fragilizaci\u00f3n por hidr\u00f3geno no est\u00e1 explicada te\u00f3ricamente. En este sentido, varios modelos tratan de explicar la propagaci\u00f3n de la fisura por la presencia en el metal de \u00e1tomos de hidr\u00f3geno.<\/li>\n<li>Generalmente se asume que el hidr\u00f3geno se genera eletroqu\u00edmicamente en la superficie del material y difunde hasta la zona en proceso de fractura. Para explicar el proceso por el cual el hidr\u00f3geno fragiliza el material existen varias teor\u00edas:\n<ul>\n<li>Cambio estructural o de fase producido por el hidr\u00f3geno.<\/li>\n<li>Plastificaci\u00f3n producida por el Hidr\u00f3geno o\u00a0<strong>hydrogen-enhanced localizad plasticity<\/strong>\u00a0(HELP).<\/li>\n<li>Reducci\u00f3n de la energ\u00eda cohesiva por el efecto del hidr\u00f3geno.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-metodologia field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Metodolog\u00eda:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Los c\u00e1lculos de\u00a0<strong>Ab-Initio<\/strong>\u00a0o por\u00a0<strong>Primeros Principios<\/strong>\u00a0se basan en el formalismo del\u00a0<strong>Funcional de la Densidad<\/strong>, la teor\u00eda de pseudo-potenciales y el teorema de Bloch. Se va a definir una base de ondas planas para representar las funciones de onda de\u00a0<strong>Kohm-Sham<\/strong>.<\/p>\n<p>En esta aproximaci\u00f3n, la precisi\u00f3n de los c\u00e1lculos viene determinada b\u00e1sicamente por dos par\u00e1metros:<\/p>\n<ul>\n<li>la m\u00e1xima energ\u00eda de corte (\u00abcut off\u00bb).<\/li>\n<li>el n\u00famero de puntos usados en espacio rec\u00edproco para representar las funciones de onda (\u00abpuntos k\u00bb).<\/li>\n<\/ul>\n<p>El problema del canje y la correlaci\u00f3n electr\u00f3nica se representa a trav\u00e9s de un funcional de canje y correlaci\u00f3n aproximado calculado con correcciones de gradientes y se utilizar\u00e1n pseudopotenciales ultra-suaves.<\/p>\n<p>Para resolver auto-consistentemente este problema, se emplear\u00e1 el c\u00f3digo de ordenador\u00a0<a href=\"http:\/\/www.castep.org\/\"><strong>CASTEP<\/strong><\/a>, donde se implementar\u00e1 un m\u00e9todo iterativo basado en las ideas de\u00a0<strong>Carr y Parrinello<\/strong>.<\/p>\n<p>En una segunda aproximaci\u00f3n se pretenden realizar c\u00e1lculos de\u00a0<strong>Din\u00e1mica Molecular Ab-Initio<\/strong>\u00a0empleando el mismo programa\u00a0<a href=\"http:\/\/www.castep.org\/\">CASTEP<\/a>.<\/p>\n<p>En estos c\u00e1lculos se considerar\u00e1 la aproximaci\u00f3n de\u00a0<strong>Born-Oppenheimer<\/strong>\u00a0que aplica los principios de la mec\u00e1nica cl\u00e1sica a los iones. Las funciones de onda de\u00a0<strong>Khon-Sham<\/strong> se desarrollar\u00e1n en una base de ondas planas.<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Javier S\u00e1nchez Montero.\u00a0Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja.\u00a0CSIC. Pedro L. de Andr\u00e9s.\u00a0Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja.\u00a0CSIC. Objetivos:\u00a0 Existe evidencia de la variaci\u00f3n de par\u00e1metros &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[102,81],"tags":[],"class_list":["post-2648","page","type-page","status-publish","hentry","category-ciencias-de-la-tierra","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e1lculos AB-Initio - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e1lculos AB-Initio - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Javier S\u00e1nchez Montero.\u00a0Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja.\u00a0CSIC. Pedro L. de Andr\u00e9s.\u00a0Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja.\u00a0CSIC. Objetivos:\u00a0 Existe evidencia de la variaci\u00f3n de par\u00e1metros ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T10:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/proyectos\\\/proyecto-calculos-ab-initio\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/en\\\/proyectos\\\/proyecto-calculos-ab-initio\\\/\",\"name\":\"C\u00e1lculos AB-Initio - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-11T07:48:06+00:00\",\"dateModified\":\"2025-08-29T10:03:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/proyectos\\\/proyecto-calculos-ab-initio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/en\\\/proyectos\\\/proyecto-calculos-ab-initio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/proyectos\\\/proyecto-calculos-ab-initio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00e1lculos AB-Initio\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e1lculos AB-Initio - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/","og_locale":"en_US","og_type":"article","og_title":"C\u00e1lculos AB-Initio - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Javier S\u00e1nchez Montero.\u00a0Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja.\u00a0CSIC. Pedro L. de Andr\u00e9s.\u00a0Instituto de Ciencias de la Construcci\u00f3n Eduardo Torroja.\u00a0CSIC. Objetivos:\u00a0 Existe evidencia de la variaci\u00f3n de par\u00e1metros ...","og_url":"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T10:03:11+00:00","og_image":[{"width":1024,"height":403,"url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/","url":"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/","name":"C\u00e1lculos AB-Initio - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-11T07:48:06+00:00","dateModified":"2025-08-29T10:03:11+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/en\/proyectos\/proyecto-calculos-ab-initio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"C\u00e1lculos AB-Initio"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2648"}],"version-history":[{"count":6,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2648\/revisions"}],"predecessor-version":[{"id":8302,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2648\/revisions\/8302"}],"up":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2648"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}