{"id":2700,"date":"2024-04-11T09:57:35","date_gmt":"2024-04-11T07:57:35","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2700"},"modified":"2025-08-29T11:56:41","modified_gmt":"2025-08-29T09:56:41","slug":"proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/","title":{"rendered":"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<ul>\n<li><strong>Alfonso Gazo Cervero y Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez<\/strong>\u00a0del grupo\u00a0<strong>G\u00cdTACA<\/strong>\u00a0(<a href=\"http:\/\/\/en\/gitaca.unex.es\/\">Grupo de Ingenier\u00eda Telem\u00e1tica Aplicada y Comunicaciones Avanzadas<\/a>) del\u00a0<strong>DISIT<\/strong>\u00a0(Departamento de Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos) de la\u00a0<a href=\"http:\/\/www.unex.es\/\">Universidad de Extremadura<\/a>, en convenio con la empresa Aplicaciones Integrales e Industriales Grupo G5.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>El principal objetivo perseguido con este proyecto es realizar una predicci\u00f3n de la evoluci\u00f3n de las infoestructuras de comunicaciones actuales, proyect\u00e1ndolas a la pr\u00f3xima d\u00e9cada para determinar, mediante t\u00e9cnicas predictivas y con la ayuda de la supercomputaci\u00f3n, las necesidades t\u00e9cnicas e inversoras, en cuanto a topolog\u00edas y tecnolog\u00edas de redes y comunicaciones se refiere. Se usar\u00e1 la supercomputaci\u00f3n para ejecutar los flujos reales de tr\u00e1fico que se producen en la Intranet extreme\u00f1a; en la red acad\u00e9mica espa\u00f1ola\u00a0<a href=\"http:\/\/www.rediris.es\/\">RedIRIS<\/a>; en la red europea\u00a0<strong>GEANT<\/strong>; y en la red americana AT&amp;T. Con estas topolog\u00edas, soportadas sobre el\u00a0<a href=\"\/en\/lusitania\/\">supercomputador LUSITANIA<\/a>, se simular\u00e1n y extrapolar\u00e1n los resultados hacia la predicci\u00f3n de sus evoluciones tecnol\u00f3gicas para poder inferir los requerimientos de necesidades y servicios en los pr\u00f3ximos a\u00f1os.<\/li>\n<li>El segundo gran objetivo del proyecto\u00a0<strong>com.info.com<\/strong>\u00a0es aplicar las lecciones aprendidas en la anterior etapa al despliegue de\u00a0<strong>FTTx<\/strong>( Fiber To The x, donde x es Home, Building, etc.) que se presenta en los \u00faltimos tiempos como la alternativa a la actual conectividad por medio de ADSL. Se prev\u00e9n muy importantes inversiones y esfuerzos en los pr\u00f3ximos a\u00f1os para el despliegue de la fibra \u00f3ptica hasta nuestros hogares y empresas. Planificar las operaciones log\u00edsticas y las inversiones se convierte en una necesidad muy importante para muchas empresas del sector que se enfrentan a elevadas barreras de entrada a este \u00e1rea de negocio por las dificultades que supone poder prever con precisi\u00f3n los costes y necesidades tecnol\u00f3gicas. En este subproyecto proponemos desarrollar un producto software que, recurriendo a la supercomputaci\u00f3n, sirva para analizar todas las posibilidades de despliegue de infoestructuras en zonas concretas antes de acometerlas para optimizar los recursos y los costes.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos-alcanzados field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objetivos alcanzados:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Simulaciones de redes reales mediante supercomputaci\u00f3n. Se estudiaron simuladores y se seleccionaron NS2 con PDNS y NS3. Se procedi\u00f3 con la configuraci\u00f3n e instalaci\u00f3n de los mismos. Utilizando la herramienta gephi para el particionado de grafos se desarroll\u00f3 una extensi\u00f3n para la generaci\u00f3n de escenarios paralelos en ns2, de modo que pudi\u00e9semos paralelizar cualquier red la cual estuviese representada como un grafo en formato GML, \u00e9sta extensi\u00f3n nos genera los archivos .tcl necesarios para la ejecuci\u00f3n de ns2 con el plugin de paralelizaci\u00f3n PDNS. Se han realizado simulaciones de redes reales mediante ambos simuladores.<\/li>\n<li>Soporte y despliegue de MIPv6. Se ha llevado a cabo la instalaci\u00f3n y configuraci\u00f3n de Omnet++ y todas sus librer\u00edas en Lusitania y la compilaci\u00f3n de XMIPv6, adem\u00e1s se a\u00f1ade Mobiwan para NS2.<\/li>\n<li>Evaluaci\u00f3n de resultados y extrapolaci\u00f3n para predicci\u00f3n de las necesidades. Se realizaron pruebas sobre escenarios reales (Red Iris, Geant y AT&amp;T) utilizando NS2 con el complemento PDNS en Lusitania y se analizaron los datos arrojados por el supercomputador en dichas simulaciones. Se han realizado pruebas con NS3 en Lusitania y se analizaron los resultados obtenidos. Por \u00faltimo se hizo una predicci\u00f3n y extrapolaci\u00f3n de resultados.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-publicaciones field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Publicaciones y congresos:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>David Cort\u00e9s-Polo, Jos\u00e9-Luis Gonz\u00e1lez-S\u00e1nchez, Alfonso Gazo-Cervero, Juan Antonio M\u00e9ndez-Barquero, Javier Fern\u00e1ndez-Ramos: Supercomputing applied to Parallel Network Simulation. 1st Workshop \u00abFuture Internet: Efficiency in high-speed networks\u00bb (W-FIERRO 2011). Cartagena. Noviembre 2011.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-taxonomy-vocabulary-4 field-type-taxonomy-term-reference field-label-hidden\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Alfonso Gazo Cervero y Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez\u00a0del grupo\u00a0G\u00cdTACA\u00a0(Grupo de Ingenier\u00eda Telem\u00e1tica Aplicada y Comunicaciones Avanzadas) del\u00a0DISIT\u00a0(Departamento de Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos) de la\u00a0Universidad de Extremadura, en &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[104,81],"tags":[],"class_list":["post-2700","page","type-page","status-publish","hentry","category-ciencias-informaticas-y-de-comunicaciones","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Alfonso Gazo Cervero y Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez\u00a0del grupo\u00a0G\u00cdTACA\u00a0(Grupo de Ingenier\u00eda Telem\u00e1tica Aplicada y Comunicaciones Avanzadas) del\u00a0DISIT\u00a0(Departamento de Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos) de la\u00a0Universidad de Extremadura, en ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T09:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/52.47.32.16\\\/proyectos\\\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\\\/\",\"url\":\"https:\\\/\\\/52.47.32.16\\\/proyectos\\\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\\\/\",\"name\":\"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-11T07:57:35+00:00\",\"dateModified\":\"2025-08-29T09:56:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/52.47.32.16\\\/proyectos\\\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/52.47.32.16\\\/proyectos\\\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/52.47.32.16\\\/proyectos\\\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/","og_locale":"en_US","og_type":"article","og_title":"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Alfonso Gazo Cervero y Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez\u00a0del grupo\u00a0G\u00cdTACA\u00a0(Grupo de Ingenier\u00eda Telem\u00e1tica Aplicada y Comunicaciones Avanzadas) del\u00a0DISIT\u00a0(Departamento de Ingenier\u00eda de Sistemas Inform\u00e1ticos y Telem\u00e1ticos) de la\u00a0Universidad de Extremadura, en ...","og_url":"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T09:56:41+00:00","og_image":[{"width":1024,"height":403,"url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/","url":"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/","name":"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-11T07:57:35+00:00","dateModified":"2025-08-29T09:56:41+00:00","breadcrumb":{"@id":"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/52.47.32.16\/proyectos\/proyecto-com-info-com-predictibilidad-de-infoestructuras-de-comunicaciones-mediante-supercomputacion-y-su-aplicacion-al-despliegue-de-redes-mipv6-y-fttx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"com.info.com: Predictibilidad de infoestructuras de comunicaciones mediante supercomputaci\u00f3n y su aplicaci\u00f3n al despliegue de redes MIPv6 y FTTx"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2700"}],"version-history":[{"count":5,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2700\/revisions"}],"predecessor-version":[{"id":8342,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2700\/revisions\/8342"}],"up":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2700"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}