{"id":2702,"date":"2024-04-11T09:57:50","date_gmt":"2024-04-11T07:57:50","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2702"},"modified":"2025-08-29T11:58:36","modified_gmt":"2025-08-29T09:58:36","slug":"proyecto-expedicion-shelios-2009","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/proyectos\/proyecto-expedicion-shelios-2009\/","title":{"rendered":"Expedici\u00f3n Shelios 2009"},"content":{"rendered":"<p style=\"text-align: justify;\">Descripci\u00f3n:<\/p>\n<p style=\"text-align: justify;\">Retransmisi\u00f3n en directo<\/p>\n<ul style=\"text-align: justify;\">\n<li>El elevado n\u00famero de visitas esperado tanto los d\u00edas que dur\u00f3 la expedici\u00f3n, como de forma especial el d\u00eda del eclipse, llev\u00f3 a los organizadores de la expedici\u00f3n a montar un cluster de m\u00e1quinas entre diversas instituciones y colaboradores para que la p\u00e1gina web estuviera siempre disponible para contar el d\u00eda a d\u00eda de la expedici\u00f3n.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Organizadores<\/p>\n<style>\/*! elementor - v3.20.0 - 10-04-2024 *\/<br \/>.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/patrocinadoresshelios.jpg\" sizes=\"(max-width: 494px) 100vw, 494px\" srcset=\"\/wp-content\/uploads\/2024\/04\/patrocinadoresshelios.jpg 494w, \/wp-content\/uploads\/2024\/04\/patrocinadoresshelios-300x41.jpg 300w\" alt=\"\" width=\"494\" height=\"68\" \/><br \/>\nObjetivos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>El principal objetivo de la expedici\u00f3n\u00a0<strong>Shelios 2009<\/strong>\u00a0fue la observaci\u00f3n y retransmisi\u00f3n del eclipse total de sol que tuvo lugar el 22 de julio de 2009 y cuya banda de totalidad ten\u00eda su m\u00e1ximo de duraci\u00f3n en el oc\u00e9ano \u00edndico.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Metodolog\u00eda:<\/p>\n<p style=\"text-align: justify;\">M\u00e9todo de retransmisi\u00f3n<\/p>\n<ul>\n<li style=\"text-align: justify;\">Tal y como se puede ver en el esquema, la imagen se enviaba desde China v\u00eda sat\u00e9lite y se recepcionaba en los servidores de las entidades espa\u00f1olas que a la vez distribu\u00edan a Internet y que mediante un Round-Robin DNS que proporcionaban los servidores ubicados en el\u00a0<strong>C\u00e9nitS<\/strong>\u00a0(Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n) serv\u00edan la web a todo el mundo de forma balanceada y con tolerancia a fallos.<\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/esquemashelios.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"\/wp-content\/uploads\/2024\/04\/esquemashelios.jpg 840w, \/wp-content\/uploads\/2024\/04\/esquemashelios-300x254.jpg 300w, \/wp-content\/uploads\/2024\/04\/esquemashelios-768x649.jpg 768w\" alt=\"\" width=\"800\" height=\"676\" \/><\/p>\n<p style=\"text-align: justify;\">El fen\u00f3meno<\/p>\n<ul>\n<li style=\"text-align: justify;\">El tercer Eclipse Total de Sol del siglo XXI en el Hemisferio Norte tuvo lugar el mi\u00e9rcoles 22 de julio de 2009 (Figura 1). El recorrido de la sombra lunar comenz\u00f3 en la India, cruz\u00f3 Nepal y China. Despu\u00e9s de abandonar el continente asi\u00e1tico pas\u00f3 por la isla Japonesa de Ryukyu muriendo en pleno Oc\u00e9ano Pac\u00edfico donde se produce el m\u00e1ximo del eclipse con una duraci\u00f3n de 6 minutos y 39 segundos con el Sol a 86 grados sobre el horizontes a las 2:35 TU.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/expedicion.banda_.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"\/wp-content\/uploads\/2024\/04\/expedicion.banda_.jpg 1004w, \/wp-content\/uploads\/2024\/04\/expedicion.banda_-300x211.jpg 300w, \/wp-content\/uploads\/2024\/04\/expedicion.banda_-768x539.jpg 768w\" alt=\"\" width=\"800\" height=\"562\" \/><\/p>\n<p style=\"text-align: justify;\">De los distintos lugares que atraviesa la banda de totalidad del eclipse el interior de China es uno de los mejores por tres principales razones:<\/p>\n<ol>\n<li style=\"text-align: justify;\">La probabilidad de tener los cielos despejados es alta.<\/li>\n<li style=\"text-align: justify;\">La probabilidad de tener tifones es muy baja.<\/li>\n<li style=\"text-align: justify;\">La duraci\u00f3n de la fase total del eclipse est\u00e1 cerca del m\u00e1ximo. Shelios ha elegido como destino final de observaci\u00f3n del eclipse los alrededores de la ciudad de Chongqing (Figura 2).<\/li>\n<\/ol>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/expedicion.mapa_.chongqing.gif\" alt=\"\" width=\"431\" height=\"279\" \/><\/p>\n<p style=\"text-align: justify;\">El itinerario previsto fue el siguiente (Figura 3):<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"text-align: justify;\">D\u00eda 0 (D12-L13 julio): Vuelo Tenerife-Madrid-Helsinki-Beijing. Descanso hotel.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 1 (M14 julio): Visitas al Templo del cielo y Observatorio Astron\u00f3mico de Beijing. Traslado de Beijing a la Gran Muralla. Parada en Gubeikou y llegada a Jinshanling (noche en albergue). Primeras explicaciones cielo nocturno y astrofotograf\u00eda.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 2 (M15 julio, 10km, 6h): Excursi\u00f3n Gran Muralla China. Jinshanling-Simatai (noche en albergue). Pr\u00e1cticas de localizaci\u00f3n constelaciones y astrofotograf\u00eda.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 3 (J16 julio, 10km, 5h): Excursi\u00f3n Gran Muralla China (secci\u00f3n de Simatai). Traslado a Beijing al final del d\u00eda. Descanso en hotel en Beijing.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 4 (V17 julio, 630km, 9h): Traslado a Pingyao con veh\u00edculos. Descando Hotel.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 5 (S18 julio): Visita Pingyao. Visita murallas y Templos del Dios y de Confucio. Descando hotel.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 6 (D19 julio, 530km, 8h): Visita al Templo de Shuanglin. Traslado a Xian con veh\u00edculos. Descanso en hotel.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 7 (L20 julio): Visita Gran Mezquita de Xian y los Guerreros de Terracota. Salida con tren nocturno hacia Chongqing (15:45).<\/li>\n<li style=\"text-align: justify;\">D\u00eda 8 (M21 julio): Llegada a Chongqing a las 6:22. Visita alrededores Huaying (cerca de Chongqing, provincia de Chongqing). Instalaci\u00f3n Campamento de observaci\u00f3n. Pr\u00e1cticas nocturnas y astrofotograf\u00eda.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 9 (M22 julio): Eclipse Total de Sol (Duraci\u00f3n 5 minutos). Acampada en Huaying.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<table style=\"width: 100%; height: 114px;\" border=\"1\" width=\"75%\" cellspacing=\"1\" cellpadding=\"1\">\n<thead>\n<tr style=\"height: 19px;\">\n<th style=\"height: 19px;\" scope=\"col\">Contactos<\/th>\n<th style=\"height: 19px;\" scope=\"col\">UT<\/th>\n<th style=\"height: 19px;\" scope=\"col\">Local<\/th>\n<th style=\"height: 19px;\" scope=\"col\">Sol<\/th>\n<th style=\"height: 19px;\" scope=\"col\"><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"height: 19px;\">\n<th style=\"height: 19px;\" scope=\"row\"><\/th>\n<td style=\"height: 19px;\"><\/td>\n<td style=\"height: 19px;\"><\/td>\n<td style=\"height: 19px;\">Altura[\u00ba]<\/td>\n<td style=\"height: 19px;\">Azimud[\u00ba]<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<th style=\"height: 19px;\" scope=\"row\">Primer<\/th>\n<td style=\"height: 19px;\">00:08<\/td>\n<td style=\"height: 19px;\">09:08<\/td>\n<td style=\"height: 19px;\">24,4<\/td>\n<td style=\"height: 19px;\">79,8<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<th style=\"height: 19px;\" scope=\"row\">Segundo<\/th>\n<td style=\"height: 19px;\">01:13<\/td>\n<td style=\"height: 19px;\">10:13<\/td>\n<td style=\"height: 19px;\">38,3<\/td>\n<td style=\"height: 19px;\">87<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<th style=\"height: 19px;\" scope=\"row\">Tercer<\/th>\n<td style=\"height: 19px;\">01:18<\/td>\n<td style=\"height: 19px;\">10:18<\/td>\n<td style=\"height: 19px;\">39,4<\/td>\n<td style=\"height: 19px;\">87,6<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<th style=\"height: 19px;\" scope=\"row\">Cuarto<\/th>\n<td style=\"height: 19px;\">02:30<\/td>\n<td style=\"height: 19px;\">11:30<\/td>\n<td style=\"height: 19px;\">51,1<\/td>\n<td style=\"height: 19px;\">97,7<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul>\n<li style=\"text-align: justify;\">D\u00eda 10 (J23 julio): Vuelo Chongqing-Beijing. Descanso hotel en Beijing.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 11 (V24 julio): Visitas Plaza Tiananmen, la Ciudad Prohibida y el Templo de los Ancestros. Visita Parques de Jinshan y Beihai. Cena en la zona de los lagos y hutong de Hou Hai. Descanso hotel en Beijing.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 12 (S25 julio): Visita Templo Lama Yonghegong y Templo de Confucio. Tarde visita vieja Torre del Tambor y Palacio de Verano. Descanso hotel en Beijing.<\/li>\n<li style=\"text-align: justify;\">D\u00eda 13 (D26 julio): Vuelo Beijing-Madrid-Tenerife.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/expedicion.ruta_.china2009.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"\/wp-content\/uploads\/2024\/04\/expedicion.ruta_.china2009.jpg 861w, \/wp-content\/uploads\/2024\/04\/expedicion.ruta_.china2009-300x200.jpg 300w, \/wp-content\/uploads\/2024\/04\/expedicion.ruta_.china2009-768x512.jpg 768w\" alt=\"\" width=\"800\" height=\"533\" \/><\/p>\n<p style=\"text-align: justify;\">Shelios se encarga de la organizaci\u00f3n te\u00f3rica y pr\u00e1ctica de la expedici\u00f3n. Se dividir\u00e1 en cinco grandes \u00e1reas que enumeramos a continuaci\u00f3n, junto con sus funciones:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u00c1rea de Ciencia y Divulgaci\u00f3n: Observaciones astron\u00f3micas y divulgaci\u00f3n de la expedici\u00f3n.<\/li>\n<li>\u00c1rea de Log\u00edstica: Planificaci\u00f3n te\u00f3rica y desarrollo in situ del viaje.<\/li>\n<li>\u00c1rea de Sanidad: Salud de los expedicionarios.<\/li>\n<li>\u00c1rea de Imagen: Difusi\u00f3n de la expedici\u00f3n. El \u00e1rea de Imagen estar\u00e1 dividida en:\n<ul>\n<li>Gabinete de prensa.<\/li>\n<li>Prensa escrita y radio.<\/li>\n<li>Imagen v\u00eddeo y fotograf\u00eda.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Tecnolog\u00eda<\/p>\n<ul style=\"text-align: justify;\">\n<li>En esta secci\u00f3n de la p\u00e1gina web se cuenta de forma resumida la tecnolog\u00eda que se ha desplegado para dar cobertura a la expedici\u00f3n en su objetivo de transmitir el\u00a0<a href=\"http:\/\/www.eclipsesolar.es\/diario.html\">d\u00eda a d\u00eda<\/a>\u00a0de los participantes en la expedici\u00f3n, y si las condiciones meteorol\u00f3gicas y t\u00e9cnicas lo permiten, retransmitir en directo el eclipse total de sol el pr\u00f3ximo d\u00eda 22 de Julio de 2009 desde China.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Ejemplo de una red<\/p>\n<ul>\n<li style=\"text-align: justify;\">El elevado n\u00famero de visitas esperado tanto los d\u00edas que dura la expedici\u00f3n, como de forma especial el d\u00eda del eclipse, ha llevado a los organizadores de la expedici\u00f3n a montar un cluster de m\u00e1quinas entre diversas instituciones y colaboradores para que la p\u00e1gina web est\u00e9 siempre disponible para contar el d\u00eda a d\u00eda de la expedici\u00f3n.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/tecnologia.red_.jpg\" sizes=\"(max-width: 474px) 100vw, 474px\" srcset=\"\/wp-content\/uploads\/2024\/04\/tecnologia.red_.jpg 474w, \/wp-content\/uploads\/2024\/04\/tecnologia.red_-300x225.jpg 300w\" alt=\"\" width=\"474\" height=\"355\" \/><\/p>\n<p style=\"text-align: justify;\">Gracias a la empresa colaboradora\u00a0<a href=\"http:\/\/www.telefonica.es\/\">Telef\u00f3nica<\/a>, la expedici\u00f3n tiene cubierta las comunicaciones. Telef\u00f3nica ha proporcionado un telefono m\u00f3vil, un modem 3G y un terminal sat\u00e9lite. Gracias al modem 3G y al terminal sat\u00e9lite podr\u00e1n, est\u00e9n donde est\u00e9n, subir las cr\u00f3nicas diarias y el d\u00eda del eclipse, retransmitirlo en directo a trav\u00e9s de internet para todo el mundo.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/tecnologia.satelite.hns9201.gif\" alt=\"\" width=\"190\" height=\"125\" \/><figcaption><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Adem\u00e1s, la colaboraci\u00f3n de Telef\u00f3nica se ha extendido a proporcionar acceso a la red de distribuci\u00f3n de contenidos Akamai, la cu\u00e1l nos permite dar soporte a un elevado n\u00famero de clientes con m\u00ednima latencia en cualquier parte del mundo en la reproducci\u00f3n de los v\u00eddeos bajo demanda y en el v\u00eddeo en directo del d\u00eda 22 de Julio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/tecnologia.akamai_low.jpg\" sizes=\"(max-width: 395px) 100vw, 395px\" srcset=\"\/wp-content\/uploads\/2024\/04\/tecnologia.akamai_low.jpg 395w, \/wp-content\/uploads\/2024\/04\/tecnologia.akamai_low-300x119.jpg 300w\" alt=\"\" width=\"395\" height=\"157\" \/><\/p>\n<p style=\"text-align: justify;\">Se cuenta adem\u00e1s con un conjunto de cam\u00e1ras de video, algunas controladas de forma remota y un equipo mezclador de v\u00eddeo que nos permitir\u00e1 d\u00eda a d\u00eda realizar las cr\u00f3nicas diarias y el d\u00eda del eclipse transmitir una mayor cantidad de sensaciones, ya que se cuenta con varias c\u00e1maras y micr\u00f3fonos.<\/p>\n<figure style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/tecnologia.montura.camara_low.jpg\" alt=\"\" width=\"138\" height=\"231\" \/><figcaption>Montura y videoc\u00e1mara usadas en el seguimiento del sol durante el eclipse<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Unos d\u00edas antes de partir, se prob\u00f3 el equipamiento completo en el\u00a0<a href=\"http:\/\/www.iac.es\/eno.php?op1=3\">Observatorio del Teide<\/a>\u00a0intentando reproducir las condiciones que se sufren durante la observaci\u00f3n del eclipse, como una bajada importante de la luz. Se realiz\u00f3 una observaci\u00f3n de la luna llena.<\/p>\n<figure style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/tecnologia.prueba.equipamiento_low.jpg\" sizes=\"(max-width: 320px) 100vw, 320px\" srcset=\"\/wp-content\/uploads\/2024\/04\/tecnologia.prueba.equipamiento_low.jpg 320w, \/wp-content\/uploads\/2024\/04\/tecnologia.prueba.equipamiento_low-300x225.jpg 300w\" alt=\"\" width=\"320\" height=\"240\" \/><figcaption>Prueba del equipamiento completo en el Observatorio del Teide antes de partir<\/figcaption><\/figure>\n<figure style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/tecnologia.prueba.luna_low.jpg\" sizes=\"(max-width: 320px) 100vw, 320px\" srcset=\"\/wp-content\/uploads\/2024\/04\/tecnologia.prueba.luna_low.jpg 320w, \/wp-content\/uploads\/2024\/04\/tecnologia.prueba.luna_low-300x225.jpg 300w\" alt=\"\" width=\"320\" height=\"240\" \/><figcaption>El equipamiento se prob\u00f3 de noche observando la luna<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Todo el equipo humano y t\u00e9cnico puesto a disposici\u00f3n de esta expedici\u00f3n y sus objetivos no habr\u00eda sido posible sin el inestimable trabajo de los\u00a0<a href=\"http:\/\/www.eclipsesolar.es\/organizadores.html\">organizadores<\/a>\u00a0y de nuestros\u00a0<a href=\"http:\/\/www.eclipsesolar.es\/colaboradores.html\">colaboradores<\/a>. A todos ellos !\u00a1Gracias!<\/p>\n<p>Noticia en los medios de comunicaci\u00f3n<\/p>\n<ul>\n<li><a href=\"http:\/\/www.hoy.es\/20090902\/sociedad\/astronomia-actividad-estrella-20090902.html\">Diario HOY<\/a><\/li>\n<li><a href=\"http:\/\/www.elperiodico.com\/default.asp?idpublicacio_PK=46&amp;idioma=CAS&amp;idnoticia_PK=628689&amp;idseccio_PK=1021\">El Peri\u00f3dico<\/a><\/li>\n<li><a href=\"http:\/\/www.abc.es\/agencias\/noticia.asp?noticia=45220&amp;titulo=La+expedici%F3n+%26quot%3BShelios+China+2009%26quot%3B+parte+el+pr%F3ximo+lunes+hacia+Beijing\">ABC<\/a><\/li>\n<li><a href=\"http:\/\/www.elmundo.es\/elmundo\/2009\/07\/21\/ciencia\/1248173151.html\">El Mundo<\/a><\/li>\n<li><a href=\"http:\/\/www.regiondigital.com\/periodico\/Juventud\/expedicion_shelios_china_2009_organizada_por_consejeria_los_jovenes_del_deporte-103672.html\">Regi\u00f3n Digital<\/a><\/li>\n<li><a href=\"http:\/\/www.universia.es\/portada\/actualidad\/noticia_actualidad.jsp?noticia=101551\">Universia<\/a><\/li>\n<li><a href=\"http:\/\/www.tendencias21.net\/China-protagoniza-el-mas-largo-eclipse-solar-del-Siglo-XXI_a3503.html\">Tendencias21<\/a><\/li>\n<li><a href=\"http:\/\/www.que.es\/ultimas-noticias\/sociedad\/200907081108-eclipse-solar-mas-largosiglo.html\">Que<\/a><\/li>\n<li><a href=\"http:\/\/www.adn.es\/tecnologia\/20090720\/NWS-0682-IAC-Asia-observaran-miercolesequipos.html\">ADN<\/a><\/li>\n<li><a href=\"http:\/\/www.eldia.es\/2009-07-27\/CRITERIOS\/12-Astrofisicos-China.htm\">El D\u00eda<\/a><\/li>\n<\/ul>\n<p>Fuentes de financiaci\u00f3n:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"\/wp-content\/uploads\/2024\/04\/logo_sheilos_0-1024x72.jpg\" sizes=\"(max-width: 800px) 100vw, 800px\" srcset=\"\/wp-content\/uploads\/2024\/04\/logo_sheilos_0-1024x72.jpg 1024w, \/wp-content\/uploads\/2024\/04\/logo_sheilos_0-300x21.jpg 300w, \/wp-content\/uploads\/2024\/04\/logo_sheilos_0-768x54.jpg 768w, \/wp-content\/uploads\/2024\/04\/logo_sheilos_0-1536x109.jpg 1536w, \/wp-content\/uploads\/2024\/04\/logo_sheilos_0.jpg 1681w\" alt=\"\" width=\"800\" height=\"56\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n: Retransmisi\u00f3n en directo El elevado n\u00famero de visitas esperado tanto los d\u00edas que dur\u00f3 la expedici\u00f3n, como de forma especial el d\u00eda del eclipse, llev\u00f3 a los organizadores de &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[102,81],"tags":[],"class_list":["post-2702","page","type-page","status-publish","hentry","category-ciencias-de-la-tierra","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expedici\u00f3n Shelios 2009 - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expedici\u00f3n Shelios 2009 - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n: Retransmisi\u00f3n en directo El elevado n\u00famero de visitas esperado tanto los d\u00edas que dur\u00f3 la expedici\u00f3n, como de forma especial el d\u00eda del eclipse, llev\u00f3 a los organizadores de ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T09:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-expedicion-shelios-2009\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-expedicion-shelios-2009\\\/\",\"name\":\"Expedici\u00f3n Shelios 2009 - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-11T07:57:50+00:00\",\"dateModified\":\"2025-08-29T09:58:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-expedicion-shelios-2009\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-expedicion-shelios-2009\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-expedicion-shelios-2009\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expedici\u00f3n Shelios 2009\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expedici\u00f3n Shelios 2009 - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/","og_locale":"en_US","og_type":"article","og_title":"Expedici\u00f3n Shelios 2009 - Fundaci\u00f3n COMPUTAEX","og_description":"Descripci\u00f3n: Retransmisi\u00f3n en directo El elevado n\u00famero de visitas esperado tanto los d\u00edas que dur\u00f3 la expedici\u00f3n, como de forma especial el d\u00eda del eclipse, llev\u00f3 a los organizadores de ...","og_url":"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T09:58:36+00:00","og_image":[{"width":1024,"height":403,"url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/","url":"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/","name":"Expedici\u00f3n Shelios 2009 - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-11T07:57:50+00:00","dateModified":"2025-08-29T09:58:36+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/proyecto-expedicion-shelios-2009\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Expedici\u00f3n Shelios 2009"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2702"}],"version-history":[{"count":9,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2702\/revisions"}],"predecessor-version":[{"id":5855,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/2702\/revisions\/5855"}],"up":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2702"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}