{"id":6754,"date":"2025-01-28T13:25:31","date_gmt":"2025-01-28T12:25:31","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=6754"},"modified":"2025-01-28T13:25:31","modified_gmt":"2025-01-28T12:25:31","slug":"xtrelan-2011","status":"publish","type":"page","link":"http:\/\/www.computaex.es\/en\/xtrelan-2011\/","title":{"rendered":"Xtrelan 2011"},"content":{"rendered":"<div class=\"field field-name-field-fecha-evento field-type-datetime field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\"><span class=\"date-display-single\">Viernes 29 de Abril de 2011, 09:00 horas.<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/www.xtrelan.es\/\">Xtrelan<\/a>\u00a0es un evento organizado por la asociaci\u00f3n A.P.I.X (Asociaci\u00f3n Promotora de la Inform\u00e1tica de Extremadura),\u00a0con la colaboraci\u00f3n y patrocinio de numerosas entidades extreme\u00f1as, entre ellas el Consorcio IdenTIC.<\/p>\n<p>Inicialmente estuvo enfocado a crear un punto de encuentro reducido para todos los que compart\u00edan sus mismas aficiones el mundo de los ordenadores y la tecnolog\u00eda.<\/p>\n<p>En la actualidad, durante la organizaci\u00f3n de\u00a0<a href=\"http:\/\/www.xtrelan.es\/\">Xtrelan 2011<\/a>, se espera tener un aforo de m\u00e1s de 1000 personas, con nuevas zonas y contenidos que convierta Xtrelan en un evento tecnol\u00f3gico completo.<\/p>\n<p>Puede acceder al resto de la informaci\u00f3n desde su p\u00e1gina web:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.xtrelan.es\/\">http:\/\/www.xtrelan.es<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-taxonomy-vocabulary-8 field-type-taxonomy-term-reference field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\"><a href=\"\/en\/conferencias\/\">Conferencias<\/a><\/div>\n<div class=\"field-item odd\"><a href=\"\/en\/asistentes\/\">Asistentes<\/a><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Viernes 29 de Abril de 2011, 09:00 horas. Xtrelan\u00a0es un evento organizado por la asociaci\u00f3n A.P.I.X (Asociaci\u00f3n Promotora de la Inform\u00e1tica de Extremadura),\u00a0con la colaboraci\u00f3n y patrocinio de numerosas entidades &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[95,97],"tags":[],"class_list":["post-6754","page","type-page","status-publish","hentry","category-asistentes","category-conferencias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xtrelan 2011 - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.computaex.es\/en\/xtrelan-2011\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xtrelan 2011 - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Viernes 29 de Abril de 2011, 09:00 horas. Xtrelan\u00a0es un evento organizado por la asociaci\u00f3n A.P.I.X (Asociaci\u00f3n Promotora de la Inform\u00e1tica de Extremadura),\u00a0con la colaboraci\u00f3n y patrocinio de numerosas entidades ...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.computaex.es\/en\/xtrelan-2011\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.computaex.es\\\/en\\\/xtrelan-2011\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/en\\\/xtrelan-2011\\\/\",\"name\":\"Xtrelan 2011 - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2025-01-28T12:25:31+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.computaex.es\\\/en\\\/xtrelan-2011\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.computaex.es\\\/en\\\/xtrelan-2011\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.computaex.es\\\/en\\\/xtrelan-2011\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xtrelan 2011\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"http:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xtrelan 2011 - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.computaex.es\/en\/xtrelan-2011\/","og_locale":"en_US","og_type":"article","og_title":"Xtrelan 2011 - Fundaci\u00f3n COMPUTAEX","og_description":"Viernes 29 de Abril de 2011, 09:00 horas. Xtrelan\u00a0es un evento organizado por la asociaci\u00f3n A.P.I.X (Asociaci\u00f3n Promotora de la Inform\u00e1tica de Extremadura),\u00a0con la colaboraci\u00f3n y patrocinio de numerosas entidades ...","og_url":"http:\/\/www.computaex.es\/en\/xtrelan-2011\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","og_image":[{"width":1024,"height":403,"url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.computaex.es\/en\/xtrelan-2011\/","url":"http:\/\/www.computaex.es\/en\/xtrelan-2011\/","name":"Xtrelan 2011 - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2025-01-28T12:25:31+00:00","breadcrumb":{"@id":"http:\/\/www.computaex.es\/en\/xtrelan-2011\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.computaex.es\/en\/xtrelan-2011\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.computaex.es\/en\/xtrelan-2011\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Xtrelan 2011"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"http:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/6754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=6754"}],"version-history":[{"count":1,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/6754\/revisions"}],"predecessor-version":[{"id":6755,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/pages\/6754\/revisions\/6755"}],"wp:attachment":[{"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=6754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=6754"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=6754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}