{"id":3995,"date":"2021-09-10T11:53:57","date_gmt":"2021-09-10T09:53:57","guid":{"rendered":"http:\/\/10.128.3.28\/?p=3995"},"modified":"2025-01-24T09:56:55","modified_gmt":"2025-01-24T08:56:55","slug":"el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/","title":{"rendered":"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00bb"},"content":{"rendered":"<p>El pr\u00f3ximo jueves 16 de septiembre, tendr\u00e1 lugar la jornada \u00ab<em><a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/eurocc-spain.res.es\/jornada-eurocc_spain_res\/\">Promoviendo el uso del HPC en la innovaci\u00f3n empresarial<\/a><\/em>\u00ab, organizada por los nodos del Centro Nacional de Competencias en Supercomputaci\u00f3n (<a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/eurocc-spain.res.es\/\">NCC<\/a>), del que forma parte\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>.<\/p>\n<p>El objetivo del evento es dar a conocer a las empresas el NCC Espa\u00f1ol, as\u00ed como las fortalezas nacionales en competencias de computaci\u00f3n de alto rendimiento (HPC,\u00a0<em>High-Performance Computing<\/em>), An\u00e1lisis de Datos de Alto Rendimiento (HPDA,\u00a0<em>High Performance Data Analytics<\/em>) e Inteligencia Artificial (AI,\u00a0<em>Artificial Intelligence<\/em>). Se persigue as\u00ed aumentar la usabilidad de estas tecnolog\u00edas en las empresas espa\u00f1olas, proporcion\u00e1ndoles una amplia cartera de servicios de supercomputaci\u00f3n adaptada a las necesidades nacionales respectivas de la industria (especialmente en relaci\u00f3n a las PYME).<\/p>\n<p>Javier Corral, ingeniero e investigador de\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>\u00a0participar\u00e1 a partir de las 10:15 horas en la mesa redonda \u00ab<em>El mapa de competencias en HPC, IA y Big Data en Espa\u00f1a<\/em>\u00ab, en la que junto Alfredo Ferrer, t\u00e9cnico e investigador del Instituto de Biocomputaci\u00f3n y Sistemas Complejos (<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.bifi.es\/es\/\">BIFI<\/a>), se destacar\u00e1 la importancia de estas tecnolog\u00edas y se expondr\u00e1n las caracter\u00edsticas actuales de dicho mapa.<\/p>\n<p>La asistencia es gratuita, pero se requiere inscripci\u00f3n previa a trav\u00e9s del correspondiente\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/eurocc-spain.res.es\/inscripcion-jornada\/\">formulario web<\/a>.<\/p>\n<p>Esta jornada se enmarca en el proyecto\u00a0<em><a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.eurocc-project.eu\/\">EuroCC<\/a>\u00a0&#8211; National Competence Centres in the framework of EuroHPC<\/em>, financiado por Empresa Com\u00fan Europea de Inform\u00e1tica de Alto Rendimiento<em>\u00a0(<\/em><em>European High-Performance Computing Joint Undertaking<\/em><em>\u00a0\u2013\u00a0<\/em><em><a class=\"views-ajax-processed-processed\" href=\"https:\/\/\/en\/eurohpc-ju.europa.eu\/\">EuroHPC-JU<\/a><\/em><em>)<\/em>\u00a0a trav\u00e9s de la convocatoria EuroHPC-04-2019 de Horizonte 2020, en virtud del acuerdo de subvenci\u00f3n No 951732.<\/p>\n<p>Ver\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/eurocc-spain.res.es\/wp-content\/uploads\/2021\/09\/Jornada-EuroCC_Spain_RES.pdf\">agenda del evento<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo jueves 16 de septiembre, tendr\u00e1 lugar la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00ab, organizada por los nodos del Centro Nacional de Competencias en Supercomputaci\u00f3n &#8230;<\/p>","protected":false},"author":1,"featured_media":3996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-3995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-supercomputacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada &quot;Promoviendo el uso del HPC en la innovaci\u00f3n empresarial&quot; - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada &quot;Promoviendo el uso del HPC en la innovaci\u00f3n empresarial&quot; - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo jueves 16 de septiembre, tendr\u00e1 lugar la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00ab, organizada por los nodos del Centro Nacional de Competencias en Supercomputaci\u00f3n ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-10T09:53:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T08:56:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.eu\/wp-content\/uploads\/2025\/01\/20210910_jornadaeurocc.png\" \/>\n\t<meta property=\"og:image:width\" content=\"177\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00bb\",\"datePublished\":\"2021-09-10T09:53:57+00:00\",\"dateModified\":\"2025-01-24T08:56:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/\"},\"wordCount\":292,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20210910_jornadaeurocc.png\",\"articleSection\":[\"Supercomputaci\u00f3n\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/\",\"url\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/\",\"name\":\"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \\\"Promoviendo el uso del HPC en la innovaci\u00f3n empresarial\\\" - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20210910_jornadaeurocc.png\",\"datePublished\":\"2021-09-10T09:53:57+00:00\",\"dateModified\":\"2025-01-24T08:56:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20210910_jornadaeurocc.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/20210910_jornadaeurocc.png\",\"width\":177,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.eu\\\/en\\\/supercomputacion\\\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \"Promoviendo el uso del HPC en la innovaci\u00f3n empresarial\" - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/","og_locale":"en_US","og_type":"article","og_title":"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \"Promoviendo el uso del HPC en la innovaci\u00f3n empresarial\" - Fundaci\u00f3n COMPUTAEX","og_description":"El pr\u00f3ximo jueves 16 de septiembre, tendr\u00e1 lugar la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00ab, organizada por los nodos del Centro Nacional de Competencias en Supercomputaci\u00f3n ...","og_url":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2021-09-10T09:53:57+00:00","article_modified_time":"2025-01-24T08:56:55+00:00","og_image":[{"width":177,"height":185,"url":"https:\/\/computaex.eu\/wp-content\/uploads\/2025\/01\/20210910_jornadaeurocc.png","type":"image\/png"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/#article","isPartOf":{"@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00bb","datePublished":"2021-09-10T09:53:57+00:00","dateModified":"2025-01-24T08:56:55+00:00","mainEntityOfPage":{"@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/"},"wordCount":292,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20210910_jornadaeurocc.png","articleSection":["Supercomputaci\u00f3n"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/","url":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/","name":"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \"Promoviendo el uso del HPC en la innovaci\u00f3n empresarial\" - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/#primaryimage"},"image":{"@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20210910_jornadaeurocc.png","datePublished":"2021-09-10T09:53:57+00:00","dateModified":"2025-01-24T08:56:55+00:00","breadcrumb":{"@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20210910_jornadaeurocc.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/20210910_jornadaeurocc.png","width":177,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.eu\/en\/supercomputacion\/el-centro-nacional-de-competencias-en-supercomputacion-ofrece-la-jornada-promoviendo-el-uso-del-hpc-en-la-innovacion-empresarial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"El Centro Nacional de Competencias en Supercomputaci\u00f3n ofrece la jornada \u00abPromoviendo el uso del HPC en la innovaci\u00f3n empresarial\u00bb"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/3995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=3995"}],"version-history":[{"count":2,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/3995\/revisions"}],"predecessor-version":[{"id":6345,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/3995\/revisions\/6345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/3996"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=3995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=3995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=3995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}