{"id":4003,"date":"2021-07-27T11:56:29","date_gmt":"2021-07-27T09:56:29","guid":{"rendered":"http:\/\/10.128.3.28\/?p=4003"},"modified":"2025-01-24T10:02:39","modified_gmt":"2025-01-24T09:02:39","slug":"la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/","title":{"rendered":"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020"},"content":{"rendered":"<p>COMPUTAEX ha presentado su memoria de actividades del ejercicio 2020. Este anuario muestra de forma detallada toda la informaci\u00f3n relativa a: los proyectos de investigaci\u00f3n e innovaci\u00f3n tecnol\u00f3gica desarrollados y soportados en\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>; los resultados de investigaci\u00f3n alcanzados; las financiaciones de proyectos competitivos obtenidas; los convenios de colaboraci\u00f3n firmados; las acciones formativas y de difusi\u00f3n realizadas; as\u00ed como los recursos de C\u00e9nitS que la\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">Fundaci\u00f3n<\/a>\u00a0pone a disposici\u00f3n de investigadores, tecn\u00f3logos e innovadores.<\/p>\n<p>La memoria est\u00e1 disponible para su descarga en formato\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/memorias-anuales\/memoria-computaex-2020\/memoria_computaex_2020_0\/\" target=\"_blank\" rel=\"noopener\">pdf<\/a>, siendo adem\u00e1s posible visualizarla de forma\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/memoria-anual\/memoria-computaex-2020\/\">online<\/a>\u00a0o acceder a ella a trav\u00e9s del hist\u00f3rico de la Fundaci\u00f3n, desde la secci\u00f3n de\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/memorias-anuales\/\">memorias anuales<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><center>\u00a0<\/center><\/p>\n<div class=\"embed-container\" data-page-height=\"700\" data-page-width=\"425\"><iframe src=\"https:\/online.anyflip.com\/yllff\/heyh\/index.html\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div data-page-height=\"700\" data-page-width=\"425\"><a class=\"views-ajax-processed-processed\" title=\"memoria_computaex_2020.pdf\" href=\"\/en\/memorias-anuales\/memoria-computaex-2020\/memoria_computaex_2020_0\/\" type=\"application\/pdf; length=22488647\">Memoria COMPUTAEX 2020<\/a><\/div>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>COMPUTAEX ha presentado su memoria de actividades del ejercicio 2020. Este anuario muestra de forma detallada toda la informaci\u00f3n relativa a: los proyectos de investigaci\u00f3n e innovaci\u00f3n tecnol\u00f3gica desarrollados y &#8230;<\/p>","protected":false},"author":1,"featured_media":4004,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-4003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-memorias-anuales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020 - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020 - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"COMPUTAEX ha presentado su memoria de actividades del ejercicio 2020. Este anuario muestra de forma detallada toda la informaci\u00f3n relativa a: los proyectos de investigaci\u00f3n e innovaci\u00f3n tecnol\u00f3gica desarrollados y ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-27T09:56:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T09:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/wp-content\/uploads\/2025\/01\/portada_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"134\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020\",\"datePublished\":\"2021-07-27T09:56:29+00:00\",\"dateModified\":\"2025-01-24T09:02:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/\"},\"wordCount\":142,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/portada_5.jpg\",\"articleSection\":[\"Memorias anuales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/\",\"name\":\"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020 - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/portada_5.jpg\",\"datePublished\":\"2021-07-27T09:56:29+00:00\",\"dateModified\":\"2025-01-24T09:02:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/portada_5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/portada_5.jpg\",\"width\":134,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/en\\\/memorias-anuales\\\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020 - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/","og_locale":"en_US","og_type":"article","og_title":"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020 - Fundaci\u00f3n COMPUTAEX","og_description":"COMPUTAEX ha presentado su memoria de actividades del ejercicio 2020. Este anuario muestra de forma detallada toda la informaci\u00f3n relativa a: los proyectos de investigaci\u00f3n e innovaci\u00f3n tecnol\u00f3gica desarrollados y ...","og_url":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2021-07-27T09:56:29+00:00","article_modified_time":"2025-01-24T09:02:39+00:00","og_image":[{"width":134,"height":185,"url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/01\/portada_5.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/#article","isPartOf":{"@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020","datePublished":"2021-07-27T09:56:29+00:00","dateModified":"2025-01-24T09:02:39+00:00","mainEntityOfPage":{"@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/"},"wordCount":142,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/portada_5.jpg","articleSection":["Memorias anuales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/","url":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/","name":"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020 - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/#primaryimage"},"image":{"@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/portada_5.jpg","datePublished":"2021-07-27T09:56:29+00:00","dateModified":"2025-01-24T09:02:39+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/portada_5.jpg","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/portada_5.jpg","width":134,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/en\/memorias-anuales\/la-fundacion-computaex-presenta-su-memoria-anual-de-actividades-correspondiente-al-ejercicio-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"La Fundaci\u00f3n COMPUTAEX presenta su memoria anual de actividades correspondiente al ejercicio 2020"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=4003"}],"version-history":[{"count":3,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4003\/revisions"}],"predecessor-version":[{"id":6354,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4003\/revisions\/6354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/4004"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=4003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}