{"id":4291,"date":"2019-05-06T13:09:56","date_gmt":"2019-05-06T11:09:56","guid":{"rendered":"http:\/\/10.128.3.28\/?p=4291"},"modified":"2025-01-24T12:26:19","modified_gmt":"2025-01-24T11:26:19","slug":"abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/","title":{"rendered":"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i"},"content":{"rendered":"<p>The\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.abc.es\/\" target=\"_blank\" rel=\"noopener\">diario ABC<\/a>\u00a0ha publicado, en su edici\u00f3n nacional de hoy lunes 6 de mayo, una entrevista al Director General de la\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\" target=\"_blank\" rel=\"noopener\">COMPUTAEX Foundation<\/a>, Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez, en el marco de su suplemento especial dedicado a la I+D+i.<\/p>\n<p>En esta entrevista Gonz\u00e1lez hace balance de la \u00faltima d\u00e9cada, destacando los logros m\u00e1s importantes alcanzados por la Fundaci\u00f3n desde sus inicios en el a\u00f1o 2009, y resumiendo las principales l\u00edneas de investigaci\u00f3n impulsadas desde\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>, el Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n. La entrevista tambi\u00e9n describe la evoluci\u00f3n de la infraestructura ofrecida a los usuarios del centro y desgrana dos de los principales proyectos de I+D+i que est\u00e1n siendo desarrollados actualmente por el equipo de ingenieros e investigadores de C\u00e9nitS:\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyecto-heritagen-ultrasecuenciacion-y-supercomputacion-para-la-unificacion-del-patrimonio-genealogico-y-genetico-extremeno-aplicacion-al-estudio-de-enfermedades-hereditarias\/\">HeritaGen<\/a>, basado en el estudio de enfermedades hereditarias mediante t\u00e9cnicas de secuenciaci\u00f3n masiva; y\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/cultivdata\/\">CultivData<\/a>, centrado en el an\u00e1lisis, dise\u00f1o y pilotaje de un prototipo de plataforma inform\u00e1tica para el \u00abcultivo\u00bb de datos abiertos y p\u00fablicos, aspirando a la excelencia en el sector agrario extreme\u00f1o.<\/p>\n<p>Ver entrevista: \u00ab<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.guiadeprensa.com\/suplementos\/idi-mayo-2019-abc\/computaex\/\" target=\"_blank\" rel=\"noopener\"><em>Queremos poner el \u201ccultivo de los datos\u201d al alcance de todos a trav\u00e9s de Big Data y HPC<\/em><\/a>\u00bb (ABC).<br \/>\nVer suplemento\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.guiadeprensa.com\/wp-content\/uploads\/2018\/03\/6may2019_IDi.pdf\" target=\"_blank\" rel=\"noopener\">I+D+i mayo 2019<\/a>\u00a0(pdf).<\/p>","protected":false},"excerpt":{"rendered":"<p>El\u00a0diario ABC\u00a0ha publicado, en su edici\u00f3n nacional de hoy lunes 6 de mayo, una entrevista al Director General de la\u00a0Fundaci\u00f3n COMPUTAEX, Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez, en el marco de su &#8230;<\/p>","protected":false},"author":1,"featured_media":4292,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/en\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"El\u00a0diario ABC\u00a0ha publicado, en su edici\u00f3n nacional de hoy lunes 6 de mayo, una entrevista al Director General de la\u00a0Fundaci\u00f3n COMPUTAEX, Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez, en el marco de su ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/en\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T11:09:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T11:26:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/abc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"97\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i\",\"datePublished\":\"2019-05-06T11:09:56+00:00\",\"dateModified\":\"2025-01-24T11:26:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/abc.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/\",\"name\":\"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/abc.jpg\",\"datePublished\":\"2019-05-06T11:09:56+00:00\",\"dateModified\":\"2025-01-24T11:26:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/abc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/abc.jpg\",\"width\":185,\"height\":97},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/en\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/","og_locale":"en_US","og_type":"article","og_title":"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i - Fundaci\u00f3n COMPUTAEX","og_description":"El\u00a0diario ABC\u00a0ha publicado, en su edici\u00f3n nacional de hoy lunes 6 de mayo, una entrevista al Director General de la\u00a0Fundaci\u00f3n COMPUTAEX, Jos\u00e9 Luis Gonz\u00e1lez S\u00e1nchez, en el marco de su ...","og_url":"https:\/\/www.computaex.es\/en\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2019-05-06T11:09:56+00:00","article_modified_time":"2025-01-24T11:26:19+00:00","og_image":[{"width":185,"height":97,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/abc.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i","datePublished":"2019-05-06T11:09:56+00:00","dateModified":"2025-01-24T11:26:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/"},"wordCount":244,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/abc.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/","url":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/","name":"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/abc.jpg","datePublished":"2019-05-06T11:09:56+00:00","dateModified":"2025-01-24T11:26:19+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/abc.jpg","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/abc.jpg","width":185,"height":97},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/sin-categoria\/abc-entrevista-al-director-general-de-la-fundacion-computaex-en-un-suplemento-especial-de-idi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"ABC entrevista al Director General de la Fundaci\u00f3n COMPUTAEX en un suplemento especial de I+D+i"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=4291"}],"version-history":[{"count":3,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4291\/revisions"}],"predecessor-version":[{"id":6472,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4291\/revisions\/6472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/4292"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=4291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=4291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=4291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}