{"id":4435,"date":"2018-09-04T08:28:57","date_gmt":"2018-09-04T06:28:57","guid":{"rendered":"http:\/\/10.128.3.28\/?p=4435"},"modified":"2025-01-23T08:59:29","modified_gmt":"2025-01-23T07:59:29","slug":"computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/","title":{"rendered":"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura"},"content":{"rendered":"<p>The Foundation\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>, junto con su centro\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>, han publicado nuevos resultados del proyecto\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/proyectos\/taxonomtic-2017\/\">TaxonomTIC<\/a>, sobre el seguimiento y an\u00e1lisis continuado del impacto y el futuro del sector TIC (Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n).<\/p>\n<p>La Fundaci\u00f3n COMPUTAEX, consciente de la importancia de las TIC y de su impacto econ\u00f3mico y social, trabaja desde el a\u00f1o 2013, en la identificaci\u00f3n y an\u00e1lisis del Sector TIC en Extremadura, publicando anualmente sus resultados. Esta labor de observatorio del Sector TIC ha continuado durante el a\u00f1o 2017 mediante el estudio de su evoluci\u00f3n en la regi\u00f3n frente a otros sectores m\u00e1s tradicionales y sus diferencias y similitudes con la evoluci\u00f3n del mismo en Espa\u00f1a y Europa. Adem\u00e1s, se ha llevado a cabo un estudio de la formaci\u00f3n profesional y universitaria TIC impartida en Extremadura y Espa\u00f1a. Finalmente se realiz\u00f3 una encuesta profesional para establecer los perfiles profesionales TIC m\u00e1s demandados dentro del sector.<\/p>\n<p>En base al an\u00e1lisis realizado, se concluye que en el a\u00f1o 2017 se constituyeron un n\u00famero de sociedades TIC inferior a la media de los diez \u00faltimos a\u00f1os, sin embargo se trata del \u00fanico sector de los estudiados que ha crecido desde el a\u00f1o 2008. La aportaci\u00f3n econ\u00f3mica del Sector TIC en Extremadura contin\u00faa siendo discreta en comparaci\u00f3n con la misma en los casos de Espa\u00f1a y Europa y se evidencia una dependencia econ\u00f3mica regional ligada a sectores tradicionales. Por otro lado, se observa un descenso generalizado de estudiantes universitarios (no s\u00f3lo en titulaciones de naturaleza TIC) y un incremento de estudiantes de formaci\u00f3n profesional.<\/p>\n<p>Los resultados pueden ser consultados en dos formatos distintos: por un lado, un\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/sites\/cenits.es\/files\/noticias\/taxonomtic_2017_resumen.pdf\/\" target=\"_blank\" rel=\"noopener\">resumen<\/a>\u00a0que contiene los aspectos m\u00e1s destacables del estudio, por el otro, la\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/sites\/cenits.es\/files\/noticias\/taxonomtic_2017_memoria.pdf\/\" target=\"_blank\" rel=\"noopener\">memoria<\/a>\u00a0completa del proyecto, donde se recoge, detalladamente y en profundidad, todo el trabajo llevado a cabo.<\/p>\n<p><a class=\"views-ajax-processed-processed\" title=\"taxonomtic_2017_resumen.pdf\" href=\"\/en\/taxonomtic_2017_resumen.pdf\/\" type=\"application\/pdf; length=534902\">TaxonomTIC 2017 &#8211; Resumen<\/a><\/p>\n<p><a class=\"views-ajax-processed-processed\" title=\"taxonomtic_2017_memoria.pdf\" href=\"\/en\/taxonomtic_2017_memoria.pdf\/\" type=\"application\/pdf; length=4401411\">TaxonomTIC 2017 &#8211; Memoria<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n\u00a0COMPUTAEX, junto con su centro\u00a0C\u00e9nitS, han publicado nuevos resultados del proyecto\u00a0TaxonomTIC, sobre el seguimiento y an\u00e1lisis continuado del impacto y el futuro del sector TIC (Tecnolog\u00edas de la Informaci\u00f3n &#8230;<\/p>","protected":false},"author":1,"featured_media":3267,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-4435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"La Fundaci\u00f3n\u00a0COMPUTAEX, junto con su centro\u00a0C\u00e9nitS, han publicado nuevos resultados del proyecto\u00a0TaxonomTIC, sobre el seguimiento y an\u00e1lisis continuado del impacto y el futuro del sector TIC (Tecnolog\u00edas de la Informaci\u00f3n ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-04T06:28:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T07:59:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.eu\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"666\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura\",\"datePublished\":\"2018-09-04T06:28:57+00:00\",\"dateModified\":\"2025-01-23T07:59:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/\"},\"wordCount\":350,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview-1.png\",\"articleSection\":[\"Proyectos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/\",\"url\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/\",\"name\":\"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview-1.png\",\"datePublished\":\"2018-09-04T06:28:57+00:00\",\"dateModified\":\"2025-01-23T07:59:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/COMPUTAEX_4k-removebg-preview-1.png\",\"width\":666,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.eu\\\/proyectos\\\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/","og_locale":"en_US","og_type":"article","og_title":"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura - Fundaci\u00f3n COMPUTAEX","og_description":"La Fundaci\u00f3n\u00a0COMPUTAEX, junto con su centro\u00a0C\u00e9nitS, han publicado nuevos resultados del proyecto\u00a0TaxonomTIC, sobre el seguimiento y an\u00e1lisis continuado del impacto y el futuro del sector TIC (Tecnolog\u00edas de la Informaci\u00f3n ...","og_url":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2018-09-04T06:28:57+00:00","article_modified_time":"2025-01-23T07:59:29+00:00","og_image":[{"width":666,"height":375,"url":"https:\/\/www.computaex.eu\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1.png","type":"image\/png"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/#article","isPartOf":{"@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura","datePublished":"2018-09-04T06:28:57+00:00","dateModified":"2025-01-23T07:59:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/"},"wordCount":350,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1.png","articleSection":["Proyectos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/","url":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/","name":"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1.png","datePublished":"2018-09-04T06:28:57+00:00","dateModified":"2025-01-23T07:59:29+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2024\/04\/COMPUTAEX_4k-removebg-preview-1.png","width":666,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.eu\/proyectos\/computaex-presenta-los-resultados-del-proyecto-taxonomtic-como-observatorio-del-sector-tic-en-extremadura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"COMPUTAEX presenta los resultados del proyecto TaxonomTIC como observatorio del sector TIC en Extremadura"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=4435"}],"version-history":[{"count":1,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4435\/revisions"}],"predecessor-version":[{"id":4436,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4435\/revisions\/4436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/3267"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=4435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=4435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=4435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}