{"id":4592,"date":"2017-06-21T08:58:42","date_gmt":"2017-06-21T06:58:42","guid":{"rendered":"http:\/\/10.128.3.28\/?p=4592"},"modified":"2025-01-23T09:10:47","modified_gmt":"2025-01-23T08:10:47","slug":"computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/","title":{"rendered":"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva"},"content":{"rendered":"<p>Investigadores de\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nits<\/a>&#8211;<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/\">COMPUTAEX<\/a>, del Servicio de Inmunolog\u00eda y Gen\u00e9tica Molecular del Hospital San Pedro de Alc\u00e1ntara y de\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/\/en\/fundesalud.es\/\" target=\"_blank\" rel=\"noopener\">Fundesalud<\/a>\u00a0(Fundaci\u00f3n para la Formaci\u00f3n e Investigaci\u00f3n de los Profesionales de la Salud de Extremadura), han dado comienzo a HERITAGEN, un novedoso proyecto sobre el estudio de enfermedades hereditarias, mediante t\u00e9cnicas de secuenciaci\u00f3n masiva.<\/p>\n<p>El objetivo general del mismo es estudiar los beneficios de la unificaci\u00f3n del patrimonio geneal\u00f3gico y gen\u00e9tico extreme\u00f1o en el estudio de enfermedades hereditarias, para reducir la ratio de variaciones de significado incierto detectadas en estudios de secuenciaci\u00f3n masiva. Para ello, se apoyar\u00e1 en el uso de infraestructuras de supercomputaci\u00f3n, as\u00ed como en t\u00e9cnicas de\u200b Big Data\u200b, que garanticen la obtenci\u00f3n de resultados en el menor tiempo posible, as\u00ed como la seguridad, la alta disponibilidad y el almacenamiento de la informaci\u00f3n tratada.<\/p>\n<p>Se estima que aproximadamente 1 de cada 200 nacimientos pueden verse afectados por las 6.000 enfermedades monog\u00e9nicas conocidas. Establecer la patogenicidad de las mutaciones detectadas mediante t\u00e9cnicas de secuenciaci\u00f3n masiva o ultra\u00adsecuenciaci\u00f3n (NGS, Next-\u00adGeneration Sequencing) en la secuencia de los genes implicados, ser\u00e1 de vital importancia para el desarrollo de terapias enmarcadas en el concepto \u200bPrecision Medicine.<\/p>\n<p>No obstante, la falta de acceso a informaci\u00f3n sobre esas variaciones hace que su patogenicidad se desconozca (VUS, \u200b Variant of Uncertain Significance\u200b ). El porcentaje de VUS puede ser reducido accediendo a la mayor cantidad de informaci\u00f3n posible sobre el gen relacionado con la enfermedad investigada, donde cobran especial importancia las mutaciones encontradas en el mismo. El principal problema es que la informaci\u00f3n se encuentra dispersa, lo cual dificulta el acceso a la misma, suponiendo un gasto econ\u00f3mico y un aumento de la dificultad procesando la informaci\u00f3n.<\/p>\n<p>El proyecto HERITAGEN est\u00e1 cofinanciado por la convocatoria de ayudas destinadas a la ejecuci\u00f3n de proyectos de investigaci\u00f3n en los Centros P\u00fablicos de investigaci\u00f3n de la Comunidad Aut\u00f3noma de Extremadura, orientados hacia las \u00e1reas estrat\u00e9gicas de la econom\u00eda regional contempladas en V Plan Regional de I+D+i (2014-2017), para la modalidad de Proyectos de investigaci\u00f3n competitivos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Investigadores de\u00a0C\u00e9nits&#8211;COMPUTAEX, del Servicio de Inmunolog\u00eda y Gen\u00e9tica Molecular del Hospital San Pedro de Alc\u00e1ntara y de\u00a0Fundesalud\u00a0(Fundaci\u00f3n para la Formaci\u00f3n e Investigaci\u00f3n de los Profesionales de la Salud de Extremadura), &#8230;<\/p>","protected":false},"author":1,"featured_media":4593,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-4592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/en\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores de\u00a0C\u00e9nits&#8211;COMPUTAEX, del Servicio de Inmunolog\u00eda y Gen\u00e9tica Molecular del Hospital San Pedro de Alc\u00e1ntara y de\u00a0Fundesalud\u00a0(Fundaci\u00f3n para la Formaci\u00f3n e Investigaci\u00f3n de los Profesionales de la Salud de Extremadura), ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/en\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-21T06:58:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T08:10:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/heritagen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva\",\"datePublished\":\"2017-06-21T06:58:42+00:00\",\"dateModified\":\"2025-01-23T08:10:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/\"},\"wordCount\":385,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/heritagen.jpg\",\"articleSection\":[\"Proyectos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/\",\"name\":\"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/heritagen.jpg\",\"datePublished\":\"2017-06-21T06:58:42+00:00\",\"dateModified\":\"2025-01-23T08:10:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/heritagen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/heritagen.jpg\",\"width\":185,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/proyectos\\\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/en\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/","og_locale":"en_US","og_type":"article","og_title":"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores de\u00a0C\u00e9nits&#8211;COMPUTAEX, del Servicio de Inmunolog\u00eda y Gen\u00e9tica Molecular del Hospital San Pedro de Alc\u00e1ntara y de\u00a0Fundesalud\u00a0(Fundaci\u00f3n para la Formaci\u00f3n e Investigaci\u00f3n de los Profesionales de la Salud de Extremadura), ...","og_url":"https:\/\/www.computaex.es\/en\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2017-06-21T06:58:42+00:00","article_modified_time":"2025-01-23T08:10:47+00:00","og_image":[{"width":185,"height":166,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/heritagen.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva","datePublished":"2017-06-21T06:58:42+00:00","dateModified":"2025-01-23T08:10:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/"},"wordCount":385,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/heritagen.jpg","articleSection":["Proyectos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/","url":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/","name":"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/heritagen.jpg","datePublished":"2017-06-21T06:58:42+00:00","dateModified":"2025-01-23T08:10:47+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/heritagen.jpg","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/heritagen.jpg","width":185,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/proyectos\/computaex-lidera-un-nuevo-proyecto-sobre-el-estudio-de-enfermedades-hereditarias-mediante-secuenciacion-genetica-masiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"COMPUTAEX lidera un nuevo proyecto sobre el estudio de enfermedades hereditarias mediante secuenciaci\u00f3n gen\u00e9tica masiva"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=4592"}],"version-history":[{"count":1,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4592\/revisions"}],"predecessor-version":[{"id":4594,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/4592\/revisions\/4594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/4593"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=4592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=4592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=4592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}