{"id":5121,"date":"2018-01-29T12:16:43","date_gmt":"2018-01-29T11:16:43","guid":{"rendered":"http:\/\/10.128.3.28\/?p=5121"},"modified":"2025-01-23T09:58:10","modified_gmt":"2025-01-23T08:58:10","slug":"el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/","title":{"rendered":"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n"},"content":{"rendered":"<p>Desde que el\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.cesga.es\/\">CESGA<\/a>\u00a0(Centro de Supercomputaci\u00f3n de Galicia) se puso en marcha en el a\u00f1o 1993, fruto de un acuerdo entre el\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.csic.es\/\">Consejo Superior de Investigaciones Cient\u00edficas<\/a>\u00a0(CSIC) y la\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.xunta.es\/\">Xunta de Galicia<\/a>, han transcurrido 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n, a trav\u00e9s de la realizaci\u00f3n de actividades basadas en la excelencia, la internacionalizaci\u00f3n, la colaboraci\u00f3n y la transferencia tecnol\u00f3gica.<\/p>\n<p>Comenz\u00f3 su andadura con el superordenador vectorial VP2400, el m\u00e1s potente de Espa\u00f1a (el n\u00famero 146 de las\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.top500.org\/\">500 instalaciones de mayor potencia del mundo<\/a>), ofreciendo servicios de c\u00e1lculo avanzado a la comunidad investigadora de las universidades gallegas, organismos e instituciones p\u00fablicas establecidos en Galicia. En la actualidad, el centro cuenta con\u00a0<a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.cesga.es\/es\/infraestructuras\/computacion\/finisterrae\">Finisterrae<\/a>, un supercomputador compuesto por 143 nodos de computaci\u00f3n, uno de los mejores de Europa y el segundo mejor de Espa\u00f1a.<\/p>\n<p><a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>\u00a0y el CESGA mantienen un\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/descripcion-la-fundacion\/convenios\/20100215-cesga\/\">convenio de colaboraci\u00f3n<\/a>, firmado en febrero de 2010, para la realizaci\u00f3n de acciones conjuntas, la utilizaci\u00f3n de los recursos de supercomputaci\u00f3n por los usuarios de los dos centros y la movilidad inter-centros de cient\u00edficos y tecn\u00f3logos.<br \/>\nM\u00e1s informaci\u00f3n:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"https:\/\/www.cesga.es\/es\/ver_nova\/idnoticia\/5207\">Edici\u00f3n especial de C\u00f3digo Cero dedicada al CESGA<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.xunta.es\/notas-de-prensa\/-\/nova\/4680\/feijoo-sublina-achega-centro-supercomputacion-desafio-facer-galicia-polo-conecemento\">Feij\u00f3o subraya la aportaci\u00f3n del Centro de Supercomputaci\u00f3n al desaf\u00edo de hacer de Galicia un polo de conocimiento que se traduzca en competitividad econ\u00f3mica y avances en la calidad de vida<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"\/en\/noticias\/190613-computaex-felicita-al-cesga-su-20-aniversario\/\">COMPUTAEX felicita al CESGA en su 20 aniversario<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Desde que el\u00a0CESGA\u00a0(Centro de Supercomputaci\u00f3n de Galicia) se puso en marcha en el a\u00f1o 1993, fruto de un acuerdo entre el\u00a0Consejo Superior de Investigaciones Cient\u00edficas\u00a0(CSIC) y la\u00a0Xunta de Galicia, han &#8230;<\/p>","protected":false},"author":1,"featured_media":5122,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-5121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-supercomputacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/en\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Desde que el\u00a0CESGA\u00a0(Centro de Supercomputaci\u00f3n de Galicia) se puso en marcha en el a\u00f1o 1993, fruto de un acuerdo entre el\u00a0Consejo Superior de Investigaciones Cient\u00edficas\u00a0(CSIC) y la\u00a0Xunta de Galicia, han ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/en\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-29T11:16:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T08:58:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/2-decadas-cesga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"135\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n\",\"datePublished\":\"2018-01-29T11:16:43+00:00\",\"dateModified\":\"2025-01-23T08:58:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/2-decadas-cesga.jpg\",\"articleSection\":[\"Supercomputaci\u00f3n\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/\",\"name\":\"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/2-decadas-cesga.jpg\",\"datePublished\":\"2018-01-29T11:16:43+00:00\",\"dateModified\":\"2025-01-23T08:58:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/2-decadas-cesga.jpg\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/2-decadas-cesga.jpg\",\"width\":185,\"height\":135},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/supercomputacion\\\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/en\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/","og_locale":"en_US","og_type":"article","og_title":"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n - Fundaci\u00f3n COMPUTAEX","og_description":"Desde que el\u00a0CESGA\u00a0(Centro de Supercomputaci\u00f3n de Galicia) se puso en marcha en el a\u00f1o 1993, fruto de un acuerdo entre el\u00a0Consejo Superior de Investigaciones Cient\u00edficas\u00a0(CSIC) y la\u00a0Xunta de Galicia, han ...","og_url":"https:\/\/www.computaex.es\/en\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2018-01-29T11:16:43+00:00","article_modified_time":"2025-01-23T08:58:10+00:00","og_image":[{"width":185,"height":135,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/2-decadas-cesga.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n","datePublished":"2018-01-29T11:16:43+00:00","dateModified":"2025-01-23T08:58:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/"},"wordCount":275,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/2-decadas-cesga.jpg","articleSection":["Supercomputaci\u00f3n"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/","url":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/","name":"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/2-decadas-cesga.jpg","datePublished":"2018-01-29T11:16:43+00:00","dateModified":"2025-01-23T08:58:10+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/2-decadas-cesga.jpg","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/2-decadas-cesga.jpg","width":185,"height":135},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/supercomputacion\/el-centro-de-supercomputacion-de-galicia-celebra-sus-20-anos-al-servicio-de-la-ciencia-y-la-innovacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"El Centro de Supercomputaci\u00f3n de Galicia celebra sus 20 a\u00f1os al servicio de la ciencia y la innovaci\u00f3n"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=5121"}],"version-history":[{"count":1,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5121\/revisions"}],"predecessor-version":[{"id":5124,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5121\/revisions\/5124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/5122"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=5121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=5121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=5121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}