{"id":5361,"date":"2012-10-10T08:43:29","date_gmt":"2012-10-10T06:43:29","guid":{"rendered":"http:\/\/10.128.3.28\/?p=5361"},"modified":"2025-01-23T10:08:21","modified_gmt":"2025-01-23T09:08:21","slug":"sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/","title":{"rendered":"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos"},"content":{"rendered":"<p>El franc\u00e9s\u00a0<a class=\"views-ajax-processed-processed\" title=\"Web oficial de Serge Haroche\" href=\"http:\/\/www.college-de-france.fr\/site\/serge-haroche\/index.htm\">Serge Haroche<\/a>, catedr\u00e1tico de F\u00edsica Cu\u00e1ntica en el\u00a0<a class=\"views-ajax-processed-processed\" title=\"Coll\u00e8ge de France\" href=\"http:\/\/www.college-de-france.fr\/\">Coll\u00e8ge de France<\/a>\u00a0y en la\u00a0<a class=\"views-ajax-processed-processed\" title=\"\u00c9cole Normale Sup\u00e9rieure\" href=\"http:\/\/www.ens.fr\/\">\u00c9cole Normale Sup\u00e9rieure<\/a>\u00a0(Par\u00eds, Francia), y el estadounidense\u00a0<a class=\"views-ajax-processed-processed\" title=\"Web oficial de David J. Wineland\" href=\"http:\/\/www.nist.gov\/pml\/div688\/grp10\/index.cfm\">David J. Wineland<\/a>, del\u00a0<a class=\"views-ajax-processed-processed\" title=\"NIST\" href=\"http:\/\/www.nist.gov\/\">National Institute of Standards and Technology<\/a>\u00a0(NIST) y la\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.colorado.edu\/\">University of Colorado Boulder<\/a>\u00a0(Colorado, EEUU), han sido galardonados con el\u00a0<a class=\"views-ajax-processed-processed\" title=\"Premio Nobel de F\u00edsica 2012\" href=\"http:\/\/\/en\/kva.se\/en\/pressroom\/Press-releases-2012\/The-Nobel-Prize-in-Physics-2012\/\">Premio Nobel de F\u00edsica 2012<\/a>\u00a0por su aportaci\u00f3n a la f\u00edsica cu\u00e1ntica a trav\u00e9s de investigaciones y m\u00e9todos innovadores en el campo de la \u00f3ptica cu\u00e1ntica.<\/p>\n<p>Seg\u00fan el comunicado de la\u00a0<a class=\"views-ajax-processed-processed\" title=\"Real Academia de Ciencias de Suecia\" href=\"http:\/\/\/en\/kva.se\/\">Real Academia de Ciencias<\/a>\u00a0de Suecia,\u00a0<em>\u00abHaroche y Wineland han abierto la puerta a una nueva era de experimentaci\u00f3n en la f\u00edsica cu\u00e1ntica al lograr la observaci\u00f3n directa de part\u00edculas cu\u00e1nticas individuales sin destruirlas. Sus innovadores m\u00e9todos han contribuido a que este campo de investigaci\u00f3n haya dado los primeros pasos hacia la fabricaci\u00f3n de un nuevo tipo de ordenador s\u00faper r\u00e1pido basado en la f\u00edsica cu\u00e1ntica\u00bb<\/em>.<\/p>\n<p>Las investigaciones de los dos galardonados\u00a0<em>\u00abtambi\u00e9n han permitido la fabricaci\u00f3n de relojes extremadamente precisos que podr\u00edan convertirse en la base futura de una nueva medida del tiempo, con una precisi\u00f3n cien veces superior a la de los relojes de cesio de hoy en\u00a0 d\u00eda\u00bb<\/em>, concluye el comunicado.<\/p>\n<p>Noticias relacionadas:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/\/en\/kva.se\/en\/pressroom\/Press-releases-2012\/The-Nobel-Prize-in-Physics-2012\/\">The Nobel Prize in Physics 2012<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.ens.fr\/spip.php?article1519\">Serge Haroche, Prix Nobel de physique 2012<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.colorado.edu\/news\/releases\/2012\/10\/09\/nobel-prize-winner-david-wineland-praised-mentor-cu-boulder-graduate\">Nobel Prize-winner David Wineland praised as mentor to CU-Boulder graduate students<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.nist.gov\/pml\/div688\/wineland-nobel.cfm\">Congratulations to David Wineland! 2012 Nobel Laureate in Physics<\/a><\/li>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.rtve.es\/noticias\/20121009\/serge-haroche-david-wineland-premio-nobel-fisica-2012\/568750.shtml\">Serge Haroche y David J. Wineland premio Nobel de F\u00edsica 2012 por sus estudios en f\u00edsica cu\u00e1ntica<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>El franc\u00e9s\u00a0Serge Haroche, catedr\u00e1tico de F\u00edsica Cu\u00e1ntica en el\u00a0Coll\u00e8ge de France\u00a0y en la\u00a0\u00c9cole Normale Sup\u00e9rieure\u00a0(Par\u00eds, Francia), y el estadounidense\u00a0David J. Wineland, del\u00a0National Institute of Standards and Technology\u00a0(NIST) y la\u00a0University of &#8230;<\/p>","protected":false},"author":1,"featured_media":5362,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-5361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuantica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/en\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"El franc\u00e9s\u00a0Serge Haroche, catedr\u00e1tico de F\u00edsica Cu\u00e1ntica en el\u00a0Coll\u00e8ge de France\u00a0y en la\u00a0\u00c9cole Normale Sup\u00e9rieure\u00a0(Par\u00eds, Francia), y el estadounidense\u00a0David J. Wineland, del\u00a0National Institute of Standards and Technology\u00a0(NIST) y la\u00a0University of ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/en\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-10T06:43:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T09:08:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/sphere-bloch-qubit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos\",\"datePublished\":\"2012-10-10T06:43:29+00:00\",\"dateModified\":\"2025-01-23T09:08:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/\"},\"wordCount\":288,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/sphere-bloch-qubit.jpg\",\"articleSection\":[\"Cu\u00e1ntica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/\",\"name\":\"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/sphere-bloch-qubit.jpg\",\"datePublished\":\"2012-10-10T06:43:29+00:00\",\"dateModified\":\"2025-01-23T09:08:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/sphere-bloch-qubit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/sphere-bloch-qubit.jpg\",\"width\":185,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/cuantica\\\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/en\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/","og_locale":"en_US","og_type":"article","og_title":"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos - Fundaci\u00f3n COMPUTAEX","og_description":"El franc\u00e9s\u00a0Serge Haroche, catedr\u00e1tico de F\u00edsica Cu\u00e1ntica en el\u00a0Coll\u00e8ge de France\u00a0y en la\u00a0\u00c9cole Normale Sup\u00e9rieure\u00a0(Par\u00eds, Francia), y el estadounidense\u00a0David J. Wineland, del\u00a0National Institute of Standards and Technology\u00a0(NIST) y la\u00a0University of ...","og_url":"https:\/\/www.computaex.es\/en\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2012-10-10T06:43:29+00:00","article_modified_time":"2025-01-23T09:08:21+00:00","og_image":[{"width":185,"height":168,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/sphere-bloch-qubit.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos","datePublished":"2012-10-10T06:43:29+00:00","dateModified":"2025-01-23T09:08:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/"},"wordCount":288,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/sphere-bloch-qubit.jpg","articleSection":["Cu\u00e1ntica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/","url":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/","name":"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/sphere-bloch-qubit.jpg","datePublished":"2012-10-10T06:43:29+00:00","dateModified":"2025-01-23T09:08:21+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/sphere-bloch-qubit.jpg","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/sphere-bloch-qubit.jpg","width":185,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/cuantica\/sentadas-las-bases-para-la-futura-creacion-de-supercomputadores-cuanticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Sentadas las bases para la futura creaci\u00f3n de supercomputadores cu\u00e1nticos"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=5361"}],"version-history":[{"count":1,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5361\/revisions"}],"predecessor-version":[{"id":5363,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5361\/revisions\/5363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/5362"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=5361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=5361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=5361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}