{"id":5373,"date":"2012-09-25T08:45:26","date_gmt":"2012-09-25T06:45:26","guid":{"rendered":"http:\/\/10.128.3.28\/?p=5373"},"modified":"2025-01-23T10:07:24","modified_gmt":"2025-01-23T09:07:24","slug":"colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/","title":{"rendered":"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX"},"content":{"rendered":"<p>Tras m\u00e1s de un a\u00f1o de trabajo, las investigaciones realizadas en colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y\u00a0<a class=\"views-ajax-processed-processed\" title=\"Centro Extreme\u00f1o de iNvestigaci\u00f3n, Innovaci\u00f3n Tecnol\u00f3gica y Supercomputaci\u00f3n\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>\u00a0sacan a la luz los primeros resultados de los procesos de secuenciaci\u00f3n gen\u00e9tica al completar el genoma humano de varios pacientes de la regi\u00f3n.<\/p>\n<p>Los estudios han logrado diagnosticar patolog\u00edas sin respuesta hasta el momento y avances en obesidad, oncolog\u00eda y dem\u00e1s enfermedades de car\u00e1cter hereditario, cuyos resultados permitir\u00e1n a los especialistas anticiparse al padecimiento de las enfermedades y aplicar tratamientos m\u00e1s eficientes durante sus fases tempranas.<\/p>\n<p>La infraestructura del\u00a0<a class=\"views-ajax-processed-processed\" title=\"Supercomputador LUSITANIA\" href=\"\/en\/cenits\/lusitania\/caracteristicas-lusitania\/\">supercomputador LUSITANIA<\/a>\u00a0aporta la capacidad de procesamiento, almacenamiento, seguridad y disponibilidad de los datos cuyo procesamiento se realiza en la actualidad de forma ininterrumpida durante algo m\u00e1s de 80 horas y gener\u00e1ndose transferencias de datos a trav\u00e9s de la red en las que se invierten 10 horas.<\/p>\n<p>Enlaces de inter\u00e9s:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" title=\"Reporta en Canal Extremadura TV\" href=\"\/en\/enlaces\/documentos\/video\/proyecto-colaboracion-ultrasecuenciacion-genetica-en-canal-extremadura-tv\/\">Reportaje en Canal Extremadura TV<\/a><\/li>\n<\/ul>\n<p>Noticias relacionadas:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" title=\"Convenio de colaboraci\u00f3n sobre investigaci\u00f3n en ultrasecuenciaci\u00f3n gen\u00e9tica\" href=\"\/en\/noticias\/convenio-colaboracion-sobre-investigacion-en-ultrasecuenciacion-genetica\/\">Convenio de colaboraci\u00f3n sobre investigaci\u00f3n en ultrasecuenciaci\u00f3n gen\u00e9tica<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Tras m\u00e1s de un a\u00f1o de trabajo, las investigaciones realizadas en colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y\u00a0C\u00e9nitS\u00a0sacan a la luz los primeros resultados de los &#8230;<\/p>","protected":false},"author":1,"featured_media":5374,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-5373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colaboracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Tras m\u00e1s de un a\u00f1o de trabajo, las investigaciones realizadas en colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y\u00a0C\u00e9nitS\u00a0sacan a la luz los primeros resultados de los ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-25T06:45:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T09:07:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/gen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX\",\"datePublished\":\"2012-09-25T06:45:26+00:00\",\"dateModified\":\"2025-01-23T09:07:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/\"},\"wordCount\":200,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/gen.jpg\",\"articleSection\":[\"Colaboraci\u00f3n\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/\",\"name\":\"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/gen.jpg\",\"datePublished\":\"2012-09-25T06:45:26+00:00\",\"dateModified\":\"2025-01-23T09:07:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/gen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/gen.jpg\",\"width\":185,\"height\":148},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/colaboracion\\\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/","og_locale":"en_US","og_type":"article","og_title":"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX","og_description":"Tras m\u00e1s de un a\u00f1o de trabajo, las investigaciones realizadas en colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y\u00a0C\u00e9nitS\u00a0sacan a la luz los primeros resultados de los ...","og_url":"https:\/\/www.computaex.es\/en\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2012-09-25T06:45:26+00:00","article_modified_time":"2025-01-23T09:07:24+00:00","og_image":[{"width":185,"height":148,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/gen.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX","datePublished":"2012-09-25T06:45:26+00:00","dateModified":"2025-01-23T09:07:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/"},"wordCount":200,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/gen.jpg","articleSection":["Colaboraci\u00f3n"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/","url":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/","name":"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/gen.jpg","datePublished":"2012-09-25T06:45:26+00:00","dateModified":"2025-01-23T09:07:24+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/gen.jpg","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/gen.jpg","width":185,"height":148},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/colaboracion\/colaboracion-entre-la-unidad-genetica-del-complejo-hospitalario-de-badajoz-y-el-centro-cenits-de-la-fundacion-computaex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Colaboraci\u00f3n entre la Unidad Gen\u00e9tica del Complejo Hospitalario de Badajoz y el centro C\u00e9nitS de la Fundaci\u00f3n COMPUTAEX"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=5373"}],"version-history":[{"count":1,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5373\/revisions"}],"predecessor-version":[{"id":5375,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5373\/revisions\/5375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/5374"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=5373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=5373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=5373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}