{"id":5556,"date":"2013-05-16T09:13:56","date_gmt":"2013-05-16T07:13:56","guid":{"rendered":"http:\/\/10.128.3.28\/?p=5556"},"modified":"2025-01-23T10:19:51","modified_gmt":"2025-01-23T09:19:51","slug":"la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos","status":"publish","type":"post","link":"https:\/\/www.computaex.es\/en\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/","title":{"rendered":"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os"},"content":{"rendered":"<p>El Centro Nacional de Referencia de Aplicaci\u00f3n de las TIC basadas en fuentes abiertas (<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.cenatic.es\/\">CENATIC<\/a>), el Centro de Cirug\u00eda de M\u00ednima Invasi\u00f3n \u00abJes\u00fas Us\u00f3n\u00bb (<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.ccmijesususon.com\/\">CCMIJU<\/a>), el Instituto de Rocas Ornamentales y Materiales de Construcci\u00f3n (<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.intromac.com\/\">INTROMAC<\/a>) y el Centro Tecnol\u00f3gico Industrial de Extremadura (<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.cetiex.es\/\">CETIEX<\/a>) dispondr\u00e1n antes de que concluya junio de conexi\u00f3n a Internet por medio de fibra \u00f3ptica a trav\u00e9s de\u00a0<a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.rediris.es\/\">Red IRIS<\/a>, permiti\u00e9ndoles aprovechar las ventajas que proporciona contar con esta infraestructura de telecomunicaciones de gran capacidad.<\/p>\n<p>Para\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/\">C\u00e9nitS<\/a>\u00a0y el supercomputador extreme\u00f1o\u00a0<a class=\"views-ajax-processed-processed\" href=\"\/en\/cenits\/lusitania\/\">LUSITANIA<\/a>, disponer de esta conexi\u00f3n es vital en tanto el centro estaba concebido como foco desde el que deb\u00edan moverse los proyectos m\u00e1s ambiciosos para la econom\u00eda y la investigaci\u00f3n en Extremadura por el volumen de los datos a tratar y la entidad de los mismos.<\/p>\n<p>Noticias relacionadas:<\/p>\n<ul>\n<li><a class=\"views-ajax-processed-processed\" href=\"http:\/\/www.abc.es\/agencias\/noticia.asp?noticia=785923\">La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos en julio &#8211; ABC<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>El Centro Nacional de Referencia de Aplicaci\u00f3n de las TIC basadas en fuentes abiertas (CENATIC), el Centro de Cirug\u00eda de M\u00ednima Invasi\u00f3n \u00abJes\u00fas Us\u00f3n\u00bb (CCMIJU), el Instituto de Rocas Ornamentales &#8230;<\/p>","protected":false},"author":1,"featured_media":5557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.computaex.es\/en\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"El Centro Nacional de Referencia de Aplicaci\u00f3n de las TIC basadas en fuentes abiertas (CENATIC), el Centro de Cirug\u00eda de M\u00ednima Invasi\u00f3n \u00abJes\u00fas Us\u00f3n\u00bb (CCMIJU), el Instituto de Rocas Ornamentales ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.computaex.es\/en\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-16T07:13:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T09:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/rct.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"55\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"COMPUTAEX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@computaex\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"COMPUTAEX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/\"},\"author\":{\"name\":\"COMPUTAEX\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\"},\"headline\":\"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os\",\"datePublished\":\"2013-05-16T07:13:56+00:00\",\"dateModified\":\"2025-01-23T09:19:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rct.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/\",\"name\":\"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rct.jpg\",\"datePublished\":\"2013-05-16T07:13:56+00:00\",\"dateModified\":\"2025-01-23T09:19:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rct.jpg\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rct.jpg\",\"width\":185,\"height\":55},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.computaex.es\\\/sin-categoria\\\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/www.computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/person\\\/8e482d5f08eeb05d7f9c491e047da2c7\",\"name\":\"COMPUTAEX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g\",\"caption\":\"COMPUTAEX\"},\"sameAs\":[\"http:\\\/\\\/10.128.3.28\"],\"url\":\"https:\\\/\\\/www.computaex.es\\\/en\\\/author\\\/admincenits\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.computaex.es\/en\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/","og_locale":"en_US","og_type":"article","og_title":"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os - Fundaci\u00f3n COMPUTAEX","og_description":"El Centro Nacional de Referencia de Aplicaci\u00f3n de las TIC basadas en fuentes abiertas (CENATIC), el Centro de Cirug\u00eda de M\u00ednima Invasi\u00f3n \u00abJes\u00fas Us\u00f3n\u00bb (CCMIJU), el Instituto de Rocas Ornamentales ...","og_url":"https:\/\/www.computaex.es\/en\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_published_time":"2013-05-16T07:13:56+00:00","article_modified_time":"2025-01-23T09:19:51+00:00","og_image":[{"width":185,"height":55,"url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/rct.jpg","type":"image\/jpeg"}],"author":"COMPUTAEX","twitter_card":"summary_large_image","twitter_creator":"@computaex","twitter_site":"@computaex","twitter_misc":{"Written by":"COMPUTAEX","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/#article","isPartOf":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/"},"author":{"name":"COMPUTAEX","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7"},"headline":"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os","datePublished":"2013-05-16T07:13:56+00:00","dateModified":"2025-01-23T09:19:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/"},"wordCount":179,"publisher":{"@id":"http:\/\/computaex.es\/#organization"},"image":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/rct.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/","url":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/","name":"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/#primaryimage"},"image":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/rct.jpg","datePublished":"2013-05-16T07:13:56+00:00","dateModified":"2025-01-23T09:19:51+00:00","breadcrumb":{"@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/#primaryimage","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/rct.jpg","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/01\/rct.jpg","width":185,"height":55},{"@type":"BreadcrumbList","@id":"https:\/\/www.computaex.es\/sin-categoria\/la-red-de-fibra-optica-conectara-cuatro-nuevos-centros-tecnologicos-extremenos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"La red de fibra \u00f3ptica conectar\u00e1 cuatro nuevos centros tecnol\u00f3gicos extreme\u00f1os"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/www.computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]},{"@type":"Person","@id":"http:\/\/computaex.es\/#\/schema\/person\/8e482d5f08eeb05d7f9c491e047da2c7","name":"COMPUTAEX","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4326f71d26728864745e3897d70bc6d2436e3971500de06e3156d3482a35fc34?s=96&d=mm&r=g","caption":"COMPUTAEX"},"sameAs":["http:\/\/10.128.3.28"],"url":"https:\/\/www.computaex.es\/en\/author\/admincenits\/"}]}},"_links":{"self":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/comments?post=5556"}],"version-history":[{"count":1,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5556\/revisions"}],"predecessor-version":[{"id":5558,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/posts\/5556\/revisions\/5558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media\/5557"}],"wp:attachment":[{"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/media?parent=5556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/categories?post=5556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.computaex.es\/en\/wp-json\/wp\/v2\/tags?post=5556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}